{"id":2724,"date":"2026-01-29T17:47:13","date_gmt":"2026-01-29T14:47:13","guid":{"rendered":"https:\/\/wiki.voka.io\/?post_type=glossary_item&#038;p=2724"},"modified":"2026-01-29T17:47:17","modified_gmt":"2026-01-29T14:47:17","slug":"necrose","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/","title":{"rendered":"Necrose"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Necrose (do grego antigo<em>\u03bd\u03b5\u03ba\u03c1\u03cc\u03c2<\/em> \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.<\/p>\n\n<p class=\"wp-block-paragraph\">As principais caracter\u00edsticas da necrose s\u00e3o o incha\u00e7o celular, desnatura\u00e7\u00e3o das prote\u00ednas e destrui\u00e7\u00e3o das organelas celulares. Durante a necrose, o conte\u00fado das c\u00e9lulas mortas \u00e9 liberado para o espa\u00e7o extracelular provocando sempre a inflama\u00e7\u00e3o, o que constitui um importante sinal diagn\u00f3stico.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>Etiologia e fisiopatologia<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A necrose \u00e9 causada pela a\u00e7\u00e3o de um irritante extremamente forte, que excede a capacidade de adapta\u00e7\u00e3o do tecido. Dependendo da causa, s\u00e3o distinguidos v\u00e1rios tipos de necrose.<\/p>\n\n<p class=\"wp-block-paragraph\">As principais causas incluem:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Vascular (isqu\u00e9mica):<\/strong> A causa mais comum. Ocorre devido \u00e0 interrup\u00e7\u00e3o ou redu\u00e7\u00e3o acentuada do suprimento sangu\u00edneo do tecido, o que leva \u00e0 hipoxia e \u00e0 morte celular. Um exemplo cl\u00e1ssico \u00e9 o enfarte do mioc\u00e1rdio.<\/li>\n\n\n\n<li><strong>Traum\u00e1tica:<\/strong> \nDestrui\u00e7\u00e3o f\u00edsica direta do tecido (golpe, rotura) ou exposi\u00e7\u00e3o a fatores f\u00edsicos (queimadura, congelamento, radia\u00e7\u00e3o).<\/li>\n\n\n\n<li><strong>T\u00f3xica:<\/strong> \nA\u00e7\u00e3o de agentes qu\u00edmicos ou toxinas. Podem ser toxinas bacterianas (por exemplo, na gangrena gasosa) ou agentes qu\u00edmicos (\u00e1cidos, \u00e1lcalis, venenos).<\/li>\n\n\n\n<li><strong>Al\u00e9rgica (imune):<\/strong> Desenvolve-se como resultado de rea\u00e7\u00f5es imunol\u00f3gicas em tecidos sensibilizados, como no fen\u00f4meno de Arthus.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x438;&#x435;-&#x438;-&#x43C;&#x43E;&#x440;&#x444;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x438;&#x435;-&#x444;&#x43E;&#x440;&#x43C;&#x44B;\"><strong>Formas cl\u00ednicas e morfol\u00f3gicas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">De acordo com as caracter\u00edsticas estruturais do tecido e a causa da morte, a necrose pode assumir v\u00e1rias formas, que diferem na apar\u00eancia e consist\u00eancia.<\/p>\n\n<p class=\"wp-block-paragraph\">Formas principais:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Necrose coagulativa (seca):<\/strong> T\u00edpica de \u00f3rg\u00e3os ricos em prote\u00ednas (cora\u00e7\u00e3o, rins, ba\u00e7o). Os tecidos necrosados tornam-se densos, secos e de cor cinza-amarelada. Os contornos estruturais do tecido s\u00e3o preservados durante algum tempo. A necrose coagulativa tamb\u00e9m ocorre quando \u00e1cidos agressivos entram em contacto com o tecido.\nO \u00e1cido provoca a desnatura\u00e7\u00e3o das prote\u00ednas e a forma\u00e7\u00e3o de uma pel\u00edcula densa e crostosa na superf\u00edcie do tecido danificado. Esta pel\u00edcula cria uma barreira protetora, impedindo a propaga\u00e7\u00e3o do \u00e1cido.<\/li>\n\n\n\n<li><strong>Necrose de liquefa\u00e7\u00e3o (coliquativa):<\/strong> \u00c9 caracterizada pela total lise da \u00e1rea tecidual com necrose, que se mostra pastosa ou l\u00edquida. \u00c9 t\u00edpico em tecidos pobres em prote\u00ednas e ricos em l\u00edquidos (por exemplo, o c\u00e9rebro em caso de acidente vascular cerebral isqu\u00e9mico). Tamb\u00e9m pode surgir quando os tecidos entram em contacto com solu\u00e7\u00f5es alcalinas concentradas. Este processo \u00e9 perigoso porque os danos no tecido continuam at\u00e9 que o \u00e1lcali seja neutralizado ou dissolvido, e \u00e1lcali consegue penetrar profundamente no tecido.<\/li>\n\n\n\n<li><strong>Gangrena:<\/strong> \nUma forma de necrose dos tecidos expostos ao meio exterior. Pode ser seca, h\u00famida ou gasosa.<\/li>\n\n\n\n<li><strong>Necrose caseosa:<\/strong> Trata-se de um tipo de necrose coagulativa em que as \u00e1reas de necrose assemelham-se com massa de queijo. \u00c9 patognom\u00f4nico de tuberculose.<\/li>\n\n\n\n<li><strong>Sequestro \u00f3sseo:<\/strong> Um fragmento \u00f3sseo desvitalizado que n\u00e3o sofre aut\u00f3lise e est\u00e1 livremente localizado no tecido \u00f3sseo saud\u00e1vel.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;-&#x438;-&#x438;&#x441;&#x445;&#x43E;&#x434;&#x44B;\"><strong>Significado cl\u00ednico e localiza\u00e7\u00e3o<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">O progn\u00f3stico da necrose depende do seu tipo, extens\u00e3o e localiza\u00e7\u00e3o. Os tecidos necrosados podem transformar-se em tecido conjuntivo (cicatriza\u00e7\u00e3o), encapsulamento (forma\u00e7\u00e3o de c\u00e1psula fibrosa) ou petrifica\u00e7\u00e3o (deposi\u00e7\u00e3o de sais de c\u00e1lcio). A necrose h\u00famida e a gangrena s\u00e3o extremamente perigosas devido \u00e0 absor\u00e7\u00e3o de produtos t\u00f3xicos da decomposi\u00e7\u00e3o, o que pode levar a uma intoxica\u00e7\u00e3o grave do organismo e \u00e0 s\u00e9psis. O tratamento requer geralmente uma interven\u00e7\u00e3o cir\u00fargica: a necrectomia, ou seja, a remo\u00e7\u00e3o dos tecidos necrosados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-2724","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Necrose: defini\u00e7\u00e3o m\u00e9dica e vis\u00e3o geral | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Necrose\" \/>\n<meta property=\"og:description\" content=\"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T14:47:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/necrose\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/necrose\\\/\",\"name\":\"Necrose: defini\u00e7\u00e3o m\u00e9dica e vis\u00e3o geral | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#website\"},\"datePublished\":\"2026-01-29T14:47:13+00:00\",\"dateModified\":\"2026-01-29T14:47:17+00:00\",\"description\":\"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/necrose\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/necrose\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/necrose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gloss\u00e1rio\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/glossario\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Necrose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/pt\\\/principios-de-publicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Necrose: defini\u00e7\u00e3o m\u00e9dica e vis\u00e3o geral | Voka Wiki","description":"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/","og_locale":"pt_PT","og_type":"article","og_title":"Necrose","og_description":"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.","og_url":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-01-29T14:47:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/","url":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/","name":"Necrose: defini\u00e7\u00e3o m\u00e9dica e vis\u00e3o geral | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/pt\/#website"},"datePublished":"2026-01-29T14:47:13+00:00","dateModified":"2026-01-29T14:47:17+00:00","description":"Necrose (do grego antigo \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2 \u2014 morto) \u00e9 um processo patol\u00f3gico de morte irrevers\u00edvel de c\u00e9lulas e tecidos num organismo vivo, causado por fatores nocivos. A necrose deve ser diferenciada da apoptose, morte celular programada e fisiol\u00f3gica que ocorre sem resposta inflamat\u00f3ria.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/pt\/glossario\/necrose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/pt\/"},{"@type":"ListItem","position":2,"name":"Gloss\u00e1rio","item":"https:\/\/wiki.voka.io\/pt\/glossario\/"},{"@type":"ListItem","position":3,"name":"Necrose"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/pt\/#website","url":"https:\/\/wiki.voka.io\/pt\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/pt\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/pt\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/wiki.voka.io\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/pt\/principios-de-publicacao\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/pt\/wp-json\/wp\/v2\/glossary_item\/2724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/pt\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/pt\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/pt\/wp-json\/wp\/v2\/media?parent=2724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}