{"id":6687,"date":"2026-04-16T13:54:10","date_gmt":"2026-04-16T10:54:10","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/dure-mere\/"},"modified":"2026-05-04T16:14:04","modified_gmt":"2026-05-04T13:14:04","slug":"dure-mere","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/","title":{"rendered":"Dure-m\u00e8re"},"content":{"rendered":"\n<p>La dure-m\u00e8re (lat. <em>dura mater<\/em>, grec<em>. pachymeninx<\/em>) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l&rsquo;enc\u00e9phale et la moelle spinale. <\/p>\n\n<p>Elle se pr\u00e9sente comme un sac fibreux dense et in\u00e9lastique qui tapisse la cavit\u00e9 cr\u00e2nienne de l&rsquo;int\u00e9rieur et sert de barri\u00e8re entre les os et le tissu nerveux d\u00e9licat.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p>Au niveau de l&rsquo;enc\u00e9phale, cette membrane poss\u00e8de une structure unique \u00e0 deux couches. La couche externe est tr\u00e8s \u00e9troitement li\u00e9e aux surfaces internes des os du cr\u00e2ne, fonctionnant pratiquement comme leur p\u00e9rioste interne. La couche interne est tourn\u00e9e vers le cerveau. Dans certaines r\u00e9gions, ces deux couches se s\u00e9parent, formant des canaux triangulaires rigides &#8211; les sinus veineux, par lesquels le sang pauvre en oxyg\u00e8ne s&rsquo;\u00e9coule du cerveau vers les veines jugulaires du cou.<\/p>\n\n<p>En outre, la couche interne forme de puissants septa (ou prolongements) qui s&rsquo;enfoncent profond\u00e9ment dans les fissures entre les sections du cerveau. Les plus grands d&rsquo;entre eux sont la faux du cerveau, qui s\u00e9pare les h\u00e9misph\u00e8res droit et gauche, et la tente du cervelet, qui s\u00e9pare les lobes occipitaux de la fosse cr\u00e2nienne post\u00e9rieure. Ces septa fixent fermement le cerveau, emp\u00eachant son d\u00e9placement critique lors de mouvements brusques de la t\u00eate.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Importance clinique<\/strong><\/h2>\n\n<p>La dure-m\u00e8re est richement innerv\u00e9e par les branches du nerf trijumeau. L&rsquo;enc\u00e9phale lui-m\u00eame n&rsquo;a pas de r\u00e9cepteurs de douleur, donc presque toute douleur intense \u00e0 la t\u00eate (y compris en cas de traumatisme ou de m\u00e9ningite) est li\u00e9e \u00e0 la tension m\u00e9canique ou \u00e0 l&rsquo;irritation chimique de la dure-m\u00e8re.<\/p>\n\n<p>En traumatologie, deux espaces critiques sont associ\u00e9s \u00e0 cette structure. L&rsquo;espace entre l&rsquo;os et la dure-m\u00e8re (\u00e9pidural) n&rsquo;existe normalement pas, mais lors de la rupture art\u00e9rielle, le sang y est projet\u00e9 sous une \u00e9norme pression, d\u00e9collant ainsi la membrane de l&rsquo;os. L&rsquo;espace sous la dure-m\u00e8re (sous-dural) est un site de collection de sang veineux lors de la rupture des veines ponts dans la pathogen\u00e8se de la formation des h\u00e9matomes sous-duraux. Les deux conditions n\u00e9cessitent une intervention neurochirurgicale d&rsquo;urgence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La dure-m\u00e8re (lat. <em>dura mater<\/em>, gr. <em>pachymeninx<\/em>) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l&rsquo;enc\u00e9phale et la moelle spinale. <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-6687","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dure-m\u00e8re : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l&#039;enc\u00e9phale et la moelle spinale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dure-m\u00e8re\" \/>\n<meta property=\"og:description\" content=\"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l&#039;enc\u00e9phale et la moelle spinale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T13:14:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/\",\"url\":\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/\",\"name\":\"Dure-m\u00e8re : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\/\/wiki.voka.io\/fr\/#website\"},\"datePublished\":\"2026-04-16T10:54:10+00:00\",\"dateModified\":\"2026-05-04T13:14:04+00:00\",\"description\":\"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l'enc\u00e9phale et la moelle spinale.\",\"breadcrumb\":{\"@id\":\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wiki.voka.io\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\/\/wiki.voka.io\/fr\/glossaire\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dure-m\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wiki.voka.io\/fr\/#website\",\"url\":\"https:\/\/wiki.voka.io\/fr\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/wiki.voka.io\/fr\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wiki.voka.io\/fr\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\/\/wiki.voka.io\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\",\"https:\/\/www.instagram.com\/voka.io\/\",\"https:\/\/www.linkedin.com\/company\/voka-io\/\",\"https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos\",\"https:\/\/www.pinterest.com\/VokaAnatomyPro\/\",\"https:\/\/www.threads.com\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dure-m\u00e8re : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l'enc\u00e9phale et la moelle spinale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/","og_locale":"fr_FR","og_type":"article","og_title":"Dure-m\u00e8re","og_description":"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l'enc\u00e9phale et la moelle spinale.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-05-04T13:14:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/","name":"Dure-m\u00e8re : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-04-16T10:54:10+00:00","dateModified":"2026-05-04T13:14:04+00:00","description":"La dure-m\u00e8re (lat. dura mater, gr. pachymeninx) est la plus externe, la plus \u00e9paisse et la plus r\u00e9sistante des trois m\u00e9ninges prot\u00e9geant l'enc\u00e9phale et la moelle spinale.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/dure-mere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Dure-m\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/6687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=6687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}