{"id":3486,"date":"2026-02-26T16:53:25","date_gmt":"2026-02-26T13:53:25","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/glandes-de-bartholin\/"},"modified":"2026-02-26T16:53:28","modified_gmt":"2026-02-26T13:53:28","slug":"glandes-de-bartholin","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/","title":{"rendered":"Glandes de Bartholin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les glandes de Bartholin (\u00e9ponyme en l&rsquo;honneur de l&rsquo;anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l&rsquo;\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.  <\/p>\n\n<p class=\"wp-block-paragraph\">Ce sont des homologues des glandes bulbo-ur\u00e9trales (cupriques) chez l&rsquo;homme.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Histologiquement, le parenchyme de la glande est constitu\u00e9 de lobules tapiss\u00e9s d&rsquo;un \u00e9pith\u00e9lium prismatique simple produisant une s\u00e9cr\u00e9tion alcaline claire, visqueuse, riche en mucine et en sialoprot\u00e9ine.  <\/p>\n\n<p class=\"wp-block-paragraph\">Le canal de sortie, long de 1,5 \u00e0 2,5 cm, est tapiss\u00e9 d&rsquo;un \u00e9pith\u00e9lium de transition et s&rsquo;ouvre par un orifice punctiforme dans la fosse naviculaire du vestibule, situ\u00e9 entre l&rsquo;hymen et les petites l\u00e8vres.  <\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;activit\u00e9 s\u00e9cr\u00e9toire est r\u00e9gul\u00e9e par le syst\u00e8me nerveux parasympathique et augmente consid\u00e9rablement pendant l&rsquo;excitation sexuelle. La fonction principale de la s\u00e9cr\u00e9tion est de lubrifier (hydrater) l&rsquo;entr\u00e9e du vagin, de prot\u00e9ger la muqueuse des microtraumatismes et de faciliter le co\u00eft. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Signification clinique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Les caract\u00e9ristiques anatomiques du canal excavateur (lumi\u00e8re \u00e9troite et longueur importante) le pr\u00e9disposent \u00e0 l&rsquo;obstruction. En cas d&rsquo;\u0153d\u00e8me inflammatoire ou de traumatisme, l&rsquo;orifice du canal est obstru\u00e9, mais la s\u00e9cr\u00e9tion se poursuit. Cela conduit \u00e0 l&rsquo;accumulation de mucus et \u00e0 la formation d&rsquo;un kyste de r\u00e9tention indolore, qui peut atteindre la taille d&rsquo;un \u0153uf de poule.   <\/p>\n\n<p class=\"wp-block-paragraph\">En cas d&rsquo;infection secondaire du contenu (le plus souvent par une flore polymicrobienne : <em>E. coli<\/em>, <em>Bacteroides spp.<\/em> ainsi que gonocoques et chlamydia), une inflammation purulente du parenchyme se d\u00e9veloppe &#8211; abc\u00e8s de la glande de bartholin (<strong>bartholinite<\/strong>). Cette affection s&rsquo;accompagne d&rsquo;un syndrome douloureux prononc\u00e9, de fi\u00e8vre et n\u00e9cessite un traitement chirurgical pour r\u00e9tablir l&rsquo;\u00e9coulement. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les glandes de Bartholin (\u00e9ponyme en l&rsquo;honneur de l&rsquo;anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l&rsquo;\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.  <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-3486","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Glandes de Bartholin : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Les glandes de Bartholin (\u00e9ponyme en l&#039;honneur de l&#039;anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l&#039;\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glandes de Bartholin\" \/>\n<meta property=\"og:description\" content=\"Les glandes de Bartholin (\u00e9ponyme en l&#039;honneur de l&#039;anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l&#039;\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T13:53:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/glandes-de-bartholin\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/glandes-de-bartholin\\\/\",\"name\":\"Glandes de Bartholin : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2026-02-26T13:53:25+00:00\",\"dateModified\":\"2026-02-26T13:53:28+00:00\",\"description\":\"Les glandes de Bartholin (\u00e9ponyme en l'honneur de l'anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l'\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/glandes-de-bartholin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/glandes-de-bartholin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/glandes-de-bartholin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glandes de Bartholin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Glandes de Bartholin : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"Les glandes de Bartholin (\u00e9ponyme en l'honneur de l'anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l'\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/","og_locale":"fr_FR","og_type":"article","og_title":"Glandes de Bartholin","og_description":"Les glandes de Bartholin (\u00e9ponyme en l'honneur de l'anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l'\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-02-26T13:53:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/","name":"Glandes de Bartholin : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-02-26T13:53:25+00:00","dateModified":"2026-02-26T13:53:28+00:00","description":"Les glandes de Bartholin (\u00e9ponyme en l'honneur de l'anatomiste danois Caspar Bartholin le Jeune, qui les a d\u00e9crites au XVIIe si\u00e8cle) sont des glandes alv\u00e9olo-tubulaires complexes paires de s\u00e9cr\u00e9tion externe situ\u00e9es dans l'\u00e9paisseur du tiers post\u00e9rieur des grandes l\u00e8vres.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/glandes-de-bartholin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Glandes de Bartholin"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/3486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=3486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}