{"id":3439,"date":"2026-02-26T16:54:25","date_gmt":"2026-02-26T13:54:25","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/myomectomie\/"},"modified":"2026-02-26T16:54:21","modified_gmt":"2026-02-26T13:54:21","slug":"myomectomie","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/","title":{"rendered":"Myomectomie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La myomectomie (du grec <em>mys<\/em> &#8211; muscle, <em>oma<\/em> &#8211; tumeur, <em>ektom\u0113<\/em> &#8211; excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l&rsquo;ut\u00e9rus et la fonction menstruelle.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">L&rsquo;essentiel de l&rsquo;intervention consiste \u00e0 diss\u00e9quer la membrane s\u00e9reuse et le myom\u00e8tre au-dessus du ganglion, \u00e0 l&rsquo;exciser (\u00e9nucl\u00e9ation) de la pseudocapsule et \u00e0 suturer soigneusement le lit couche par couche. L&rsquo;h\u00e9mostase et la juxtaposition pr\u00e9cise des couches de myom\u00e8tre constituent une \u00e9tape critique pour la formation d&rsquo;une cicatrice solide et compl\u00e8te, capable de r\u00e9sister \u00e0 l&rsquo;\u00e9tirement lors de futures grossesses. En fonction de la localisation des ganglions (sous-muqueux, intramuraux, sous-s\u00e9reux), l&rsquo;acc\u00e8s est choisi : hyst\u00e9rectoscopie, laparoscopie ou laparotomie.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Signification clinique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La myomectomie est le traitement de r\u00e9f\u00e9rence des <strong>myomes<\/strong> ut\u00e9rins symptomatiques chez les femmes en \u00e2ge de procr\u00e9er qui envisagent une grossesse. L&rsquo;intervention chirurgicale \u00e9limine les sympt\u00f4mes (saignements, douleurs, compression des organes adjacents) et r\u00e9tablit l&rsquo;anatomie de l&rsquo;ut\u00e9rus. Les principaux risques sont la perte de sang pendant l&rsquo;op\u00e9ration, la formation d&rsquo;adh\u00e9rences et le risque de r\u00e9cidive (croissance de nouveaux ganglions) dans 15 \u00e0 30 % des cas dans les 5 ans suivant l&rsquo;op\u00e9ration.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La myomectomie (du grec <em>mys<\/em> &#8211; muscle, <em>oma<\/em> &#8211; tumeur, <em>ektom\u0113<\/em> &#8211; excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l&rsquo;ut\u00e9rus et la fonction menstruelle.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-3439","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Myomectomie : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l&#039;ut\u00e9rus et la fonction menstruelle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Myomectomie\" \/>\n<meta property=\"og:description\" content=\"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l&#039;ut\u00e9rus et la fonction menstruelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/myomectomie\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/myomectomie\\\/\",\"name\":\"Myomectomie : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2026-02-26T13:54:25+00:00\",\"description\":\"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l'ut\u00e9rus et la fonction menstruelle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/myomectomie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/myomectomie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/myomectomie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Myomectomie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Myomectomie : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l'ut\u00e9rus et la fonction menstruelle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/","og_locale":"fr_FR","og_type":"article","og_title":"Myomectomie","og_description":"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l'ut\u00e9rus et la fonction menstruelle.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/","name":"Myomectomie : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-02-26T13:54:25+00:00","description":"La myomectomie (du grec mys - muscle, oma - tumeur, ektom\u0113 - excision) est une op\u00e9ration de reconstruction et de pr\u00e9servation des organes plastiques visant \u00e0 retirer chirurgicalement les nodules de l\u00e9iomyome tout en pr\u00e9servant le corps de l'ut\u00e9rus et la fonction menstruelle.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/myomectomie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Myomectomie"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/3439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=3439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}