{"id":2901,"date":"2026-01-29T17:22:52","date_gmt":"2026-01-29T14:22:52","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/macule\/"},"modified":"2026-01-29T17:22:54","modified_gmt":"2026-01-29T14:22:54","slug":"macule","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/","title":{"rendered":"Macula"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une macule (du latin <em>macula<\/em> &#8211; tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d&rsquo;une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e. <\/p>\n\n<p class=\"wp-block-paragraph\">La principale caract\u00e9ristique de la tache est qu&rsquo;elle ne d\u00e9passe pas le niveau de la peau saine et qu&rsquo;elle n&rsquo;est pas enfonc\u00e9e (non palpable). Si vous fermez les yeux et passez votre doigt sur la tache, vous ne sentirez aucun changement dans le relief de la peau. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Le changement de couleur peut \u00eatre caus\u00e9 par divers m\u00e9canismes :  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Taches vasculaires :<\/strong> associ\u00e9es \u00e0 une dilatation temporaire ou persistante des vaisseaux sanguins (ros\u00e9ole, \u00e9ryth\u00e8me, t\u00e9langiectasie). Elles disparaissent ou p\u00e2lissent \u00e0 la pression (diascopie).   <\/li>\n\n\n\n<li><strong>Taches h\u00e9morragiques :<\/strong> se produisent lorsque des globules rouges s&rsquo;\u00e9chappent des vaisseaux et p\u00e9n\u00e8trent dans les tissus (p\u00e9t\u00e9chies, ecchymoses). Elles ne disparaissent pas sous l&rsquo;effet de la pression.   <\/li>\n\n\n\n<li><strong>Taches de vieillesse :<\/strong> associ\u00e9es \u00e0 des changements dans la quantit\u00e9 de pigments de m\u00e9lanine. Elles peuvent \u00eatre hyperpigment\u00e9es (taches de rousseur, chloasma) ou d\u00e9pigment\u00e9es (vitiligo). <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Signification clinique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La taille de la tache a une incidence sur la terminologie : les taches d&rsquo;un diam\u00e8tre inf\u00e9rieur ou \u00e9gal \u00e0 1 \u00e0 2 cm sont g\u00e9n\u00e9ralement appel\u00e9es ros\u00e9ole (si elles sont vasculaires) ou simplement macules, tandis que les foyers plus importants sont appel\u00e9s \u00e9ryth\u00e8mes. Les macules sont l&rsquo;\u00e9l\u00e9ment le plus courant de l&rsquo;\u00e9ruption cutan\u00e9e et apparaissent dans un grand nombre de maladies : des infections (rougeole, rub\u00e9ole) aux r\u00e9actions allergiques. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une macule (du latin <em>macula<\/em> &#8211; tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d&rsquo;une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e. <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-2901","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Macula : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d&#039;une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Macula\" \/>\n<meta property=\"og:description\" content=\"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d&#039;une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T14:22:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/macule\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/macule\\\/\",\"name\":\"Macula : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-29T14:22:52+00:00\",\"dateModified\":\"2026-01-29T14:22:54+00:00\",\"description\":\"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d'une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/macule\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/macule\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/macule\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Macula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Macula : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d'une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/","og_locale":"fr_FR","og_type":"article","og_title":"Macula","og_description":"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d'une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-01-29T14:22:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/","name":"Macula : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-01-29T14:22:52+00:00","dateModified":"2026-01-29T14:22:54+00:00","description":"Une macule (du latin macula - tache) est un \u00e9l\u00e9ment morphologique primaire, d\u00e9pourvu de cellules, d'une \u00e9ruption cutan\u00e9e caract\u00e9ris\u00e9e par un changement de couleur de la peau dans une zone limit\u00e9e.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/macule\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Macula"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}