{"id":2722,"date":"2026-01-29T17:47:13","date_gmt":"2026-01-29T14:47:13","guid":{"rendered":"https:\/\/wiki.voka.io\/?post_type=glossary_item&#038;p=2722"},"modified":"2026-01-29T17:47:15","modified_gmt":"2026-01-29T14:47:15","slug":"necrose","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/","title":{"rendered":"N\u00e9crose"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La n\u00e9crose (du grec ancien <em>\u03bd\u03b5\u03ba\u03c1\u03cc\u03c2<\/em> \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.<\/p>\n\n<p class=\"wp-block-paragraph\">Les caract\u00e9ristiques cl\u00e9s de la n\u00e9crose incluent le gonflement cellulaire, la d\u00e9naturation des prot\u00e9ines et la destruction des organites cellulaires. La lib\u00e9ration du contenu des cellules mortes dans l\u2019espace environnant d\u00e9clenche syst\u00e9matiquement une inflammation, ce qui constitue un signe diagnostique important.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La n\u00e9crose repose sur l\u2019exposition \u00e0 un stimulus extr\u00eame d\u00e9passant les capacit\u00e9s adaptatives du tissu. Selon la cause, plusieurs types de n\u00e9crose sont distingu\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Les principales causes sont les suivantes\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Vasculaire (isch\u00e9mique) : <\/strong> La cause la plus fr\u00e9quente. R\u00e9sulte de l\u2019arr\u00eat ou d\u2019une diminution brutale de l\u2019apport sanguin, entra\u00eenant une hypoxie et la mort cellulaire. Exemple classique : l\u2019infarctus du myocarde.\n<\/li>\n\n\n\n<li><strong>Traumatique : <\/strong>  Destruction physique directe du tissu (choc, d\u00e9chirure) ou exposition \u00e0 des facteurs physiques (br\u00fblure, gelure, rayonnement).<\/li>\n\n\n\n<li><strong>Toxique : <\/strong> Action de substances chimiques ou de toxines. Cela peut inclure des toxines bact\u00e9riennes (par exemple, dans la gangr\u00e8ne gazeuse) ou des agents chimiques (acides, bases, poisons).<\/li>\n\n\n\n<li><strong>Allergique (immunitaire) :<\/strong> Se d\u00e9veloppe \u00e0 la suite de r\u00e9actions immunitaires dans des tissus sensibilis\u00e9s, par exemple, dans le ph\u00e9nom\u00e8ne d\u2019Arthus.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x438;&#x435;-&#x438;-&#x43C;&#x43E;&#x440;&#x444;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x438;&#x435;-&#x444;&#x43E;&#x440;&#x43C;&#x44B;\"><strong>Formes cliniques et morphologiques<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En fonction des caract\u00e9ristiques structurelles du tissu et de la cause de la mort, la n\u00e9crose peut prendre diff\u00e9rentes formes, qui varient par leur apparence et leur consistance.<\/p>\n\n<p class=\"wp-block-paragraph\">Principales formes :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>N\u00e9crose coagulative (s\u00e8che) :<\/strong> Caract\u00e9ristique des organes riches en prot\u00e9ines (c\u0153ur, reins, rate). Les tissus n\u00e9cros\u00e9s deviennent denses, secs, de couleur gris-jaune. Les contours structuraux du tissu sont pr\u00e9serv\u00e9s pendant un certain temps. \u00c9galement, la n\u00e9crose coagulative se forme lors de l\u2019exposition des tissus \u00e0 des acides agressifs. L\u2019acide provoque une d\u00e9naturation des prot\u00e9ines et la formation d\u2019une pellicule dense, semblable \u00e0 une cro\u00fbte, \u00e0 la surface du tissu l\u00e9s\u00e9. Cette pellicule agit comme une barri\u00e8re protectrice, emp\u00eachant la propagation ult\u00e9rieure de l\u2019acide.<\/li>\n\n\n\n<li><strong>N\u00e9crose colliquative (humide) : <\/strong> R\u00e9sulte d\u2019une liqu\u00e9faction enzymatique des tissus morts, formant une masse liquide ou p\u00e2teuse. Typique des tissus pauvres en prot\u00e9ines et riches en liquide (par exemple, le cerveau lors d\u2019un accident vasculaire c\u00e9r\u00e9bral isch\u00e9mique). Elle se d\u00e9veloppe \u00e9galement lors du contact des tissus avec des solutions alcalines concentr\u00e9es. Ce processus est dangereux car la l\u00e9sion tissulaire se poursuit jusqu\u2019\u00e0 ce que l\u2019alcali soit neutralis\u00e9 ou dilu\u00e9, et l\u2019alcali peut p\u00e9n\u00e9trer profond\u00e9ment dans les tissus.<\/li>\n\n\n\n<li><strong>Gangr\u00e8ne : <\/strong> Forme de n\u00e9crose des tissus en contact avec l\u2019environnement externe. Peut \u00eatre s\u00e8che, humide ou gazeuse.<\/li>\n\n\n\n<li><strong>N\u00e9crose cas\u00e9euse (fromageuse) : <\/strong> Variante de la n\u00e9crose coagulative, o\u00f9 le tissu mort ressemble \u00e0 une masse friable, semblable \u00e0 du fromage. Pathognomonique de la tuberculose.<\/li>\n\n\n\n<li><strong>S\u00e9questre : <\/strong> Fragment de tissu osseux mort, non soumis \u00e0 l\u2019autolyse, situ\u00e9 librement parmi l\u2019os vivant.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;-&#x438;-&#x438;&#x441;&#x445;&#x43E;&#x434;&#x44B;\"><strong>Signification clinique et r\u00e9sultats<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019issue de la n\u00e9crose d\u00e9pend de son type, de son \u00e9tendue et de sa localisation. Les tissus n\u00e9cros\u00e9s peuvent subir une organisation avec remplacement par du tissu conjonctif (cicatrication), une encapsulation (formation d\u2019une capsule fibreuse) ou une p\u00e9triification (d\u00e9p\u00f4t de sels de calcium). La n\u00e9crose humide et la gangr\u00e8ne sont extr\u00eamement dangereuses en raison de l\u2019absorption de produits toxiques de d\u00e9gradation, pouvant entra\u00eener une intoxication s\u00e9v\u00e8re de l\u2019organisme et un sepsis. Le traitement n\u00e9cessite souvent une intervention chirurgicale \u2014 la n\u00e9crosectomie, c\u2019est-\u00e0-dire l\u2019excision des tissus non viables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-2722","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>N\u00e9crose : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e9crose\" \/>\n<meta property=\"og:description\" content=\"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T14:47:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/necrose\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/necrose\\\/\",\"name\":\"N\u00e9crose : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-29T14:47:13+00:00\",\"dateModified\":\"2026-01-29T14:47:15+00:00\",\"description\":\"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/necrose\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/necrose\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/necrose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00e9crose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"N\u00e9crose : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/","og_locale":"fr_FR","og_type":"article","og_title":"N\u00e9crose","og_description":"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-01-29T14:47:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/","name":"N\u00e9crose : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-01-29T14:47:13+00:00","dateModified":"2026-01-29T14:47:15+00:00","description":"La n\u00e9crose (du grec ancien \u03bd\u03b5\u03ba\u03c1\u03cc\u03c2, \u00ab mort \u00bb) est un processus pathologique de mort irr\u00e9versible des cellules et des tissus dans un organisme vivant, provoqu\u00e9 par l\u2019action de facteurs l\u00e9sionnels. La n\u00e9crose doit \u00eatre distingu\u00e9e de l\u2019apoptose, une mort cellulaire programm\u00e9e et physiologique qui se d\u00e9roule sans r\u00e9action inflammatoire.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/necrose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"N\u00e9crose"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/2722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}