{"id":2523,"date":"2026-01-29T17:19:02","date_gmt":"2026-01-29T14:19:02","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/restauration-dentaire\/"},"modified":"2026-03-03T11:50:16","modified_gmt":"2026-03-03T08:50:16","slug":"restauration-dentaire","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/","title":{"rendered":"Restauration dentaire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La restauration dentaire (du latin <em>restauratio<\/em> \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d&rsquo;une blessure. L&rsquo;objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x430;&#x441;&#x441;&#x438;&#x444;&#x438;&#x43A;&#x430;&#x446;&#x438;&#x44F;-&#x440;&#x435;&#x441;&#x442;&#x430;&#x432;&#x440;&#x430;&#x446;&#x438;&#x439;\"><strong>Classification des restaurations\u00a0:<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Restaurations directes<\/strong>\u00a0: fabriqu\u00e9es directement dans la cavit\u00e9 orale\u00a0;<\/li>\n\n\n\n<li><strong>Restaurations indirectes<\/strong> (facettes, inlays, onlays, couronnes, bridges)\u00a0: fabriqu\u00e9es dans un laboratoire dentaire puis plac\u00e9es dans la cavit\u00e9 orale.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c9tiologie et physiopathologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Les mat\u00e9riaux d&rsquo;obturation modernes (composites photopolym\u00e9risables) cr\u00e9ent une liaison avec les tissus dentaires (connue sous le nom d&rsquo;adh\u00e9sion) en formant une couche hybride \u00e0 l&rsquo;aide d&rsquo;un syst\u00e8me adh\u00e9sif. Les ciments verre ionom\u00e8res cr\u00e9ent une liaison chimique avec les tissus dentaires. Cela permet non seulement de fermer le d\u00e9faut mais aussi de restaurer la r\u00e9sistance m\u00e9canique de la couronne dentaire. Une restauration correctement plac\u00e9e isole compl\u00e8tement la dentine de l&rsquo;exposition aux environnements ext\u00e9rieurs, pr\u00e9venant l&rsquo;infiltration bact\u00e9rienne dans la dent et restaurant la forme et la fonction d&rsquo;une ou de plusieurs dents.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Importance clinique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La qualit\u00e9 de la restauration est d\u00e9termin\u00e9e par son ajustement aux bords du d\u00e9faut dans les tissus durs de la dent. Les caries secondaires se d\u00e9veloppent en pr\u00e9sence de micro-fissures (perte d&rsquo;imperm\u00e9abilit\u00e9). La long\u00e9vit\u00e9 de la restauration d\u00e9pend de la quantit\u00e9 de tissu dentaire restant, du respect du protocole de restauration par le dentiste, de la qualit\u00e9 des mat\u00e9riaux utilis\u00e9s, et de la conformit\u00e9 du patient aux r\u00e8gles d&rsquo;hygi\u00e8ne bucco-dentaire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La restauration dentaire (du latin <em>restauratio<\/em> \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d&rsquo;une blessure. L&rsquo;objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-2523","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Restauration dentaire : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d&#039;une blessure. L&#039;objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restauration dentaire\" \/>\n<meta property=\"og:description\" content=\"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d&#039;une blessure. L&#039;objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T08:50:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/restauration-dentaire\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/restauration-dentaire\\\/\",\"name\":\"Restauration dentaire : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-29T14:19:02+00:00\",\"dateModified\":\"2026-03-03T08:50:16+00:00\",\"description\":\"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d'une blessure. L'objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/restauration-dentaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/restauration-dentaire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/restauration-dentaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restauration dentaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Restauration dentaire : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d'une blessure. L'objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Restauration dentaire","og_description":"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d'une blessure. L'objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-03-03T08:50:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/","name":"Restauration dentaire : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2026-01-29T14:19:02+00:00","dateModified":"2026-03-03T08:50:16+00:00","description":"La restauration dentaire (du latin restauratio \u2013 restauration) est un mat\u00e9riau biocompatible sp\u00e9cialis\u00e9 utilis\u00e9 pour le remplissage de cavit\u00e9s dans la dent r\u00e9sultant du traitement des caries ou d'une blessure. L'objectif principal de la restauration dentaire est de restaurer la forme anatomique et la fonction, et de sceller les tissus dentaires.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/restauration-dentaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Restauration dentaire"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=2523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}