{"id":1227,"date":"2025-09-08T11:43:37","date_gmt":"2025-09-08T08:43:37","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/%d1%8d%d0%bc%d0%b1%d0%be%d0%bb%d0%b8%d0%b7%d0%b0%d1%86%d0%b8%d1%8f\/"},"modified":"2025-10-13T12:32:31","modified_gmt":"2025-10-13T09:32:31","slug":"embolisation","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/","title":{"rendered":"Embolisation"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.<\/p>\n\n<p class=\"wp-block-paragraph\">La proc\u00e9dure est r\u00e9alis\u00e9e sous contr\u00f4le d\u2019imagerie radiologique, le plus souvent par angiographie. L\u2019objectif principal de l\u2019embolisation est de stopper ou de r\u00e9duire significativement le flux sanguin dans une zone sp\u00e9cifique du r\u00e9seau vasculaire afin d\u2019arr\u00eater une h\u00e9morragie ou de couper l\u2019approvisionnement sanguin d\u2019une l\u00e9sion pathologique (par exemple, une tumeur).<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43C;&#x435;&#x442;&#x43E;&#x434;&#x438;&#x43A;&#x430;-&#x438;-&#x43C;&#x430;&#x442;&#x435;&#x440;&#x438;&#x430;&#x43B;&#x44B;\"><strong>M\u00e9thodologie et mat\u00e9riaux<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019acc\u00e8s au vaisseau cible est obtenu par une petite ponction, g\u00e9n\u00e9ralement au niveau de l\u2019art\u00e8re f\u00e9morale ou radiale. Un cath\u00e9ter fin est introduit \u00e0 travers cette ponction et guid\u00e9 jusqu\u2019\u00e0 la zone cibl\u00e9e sous contr\u00f4le radiographique. Une fois le cath\u00e9ter correctement positionn\u00e9, des mat\u00e9riaux embolisants sont administr\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Le choix du mat\u00e9riau d\u00e9pend de l\u2019objectif, de la taille et de l\u2019emplacement du vaisseau :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Coils.<\/strong> Des coils m\u00e9talliques (souvent en platine) qui, une fois introduits dans le vaisseau, s\u2019enroulent et forment un thrombus, bloquant le flux sanguin.<\/li>\n\n\n\n<li><strong>Microsph\u00e8res (particules).<\/strong> De petites billes de polym\u00e8res synth\u00e9tiques qui obstruent les petites art\u00e8res ; souvent utilis\u00e9es pour l\u2019embolisation de tumeurs.<\/li>\n\n\n\n<li><strong>Agents embolisants liquides.<\/strong> Des compositions adh\u00e9sives ou polym\u00e8res inject\u00e9es sous forme liquide et qui durcissent \u00e0 l\u2019int\u00e9rieur du vaisseau, cr\u00e9ant une occlusion durable.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Importance clinique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019embolisation constitue une alternative majeure \u00e0 la chirurgie ouverte traditionnelle et trouve des applications dans de nombreux domaines m\u00e9dicaux.<\/p>\n\n<p class=\"wp-block-paragraph\">Principales indications :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Neurochirurgie.<\/strong> Pour exclure du flux sanguin les an\u00e9vrismes des vaisseaux c\u00e9r\u00e9braux ou les malformations art\u00e9rioveineuses, pr\u00e9venant ainsi leur rupture.<\/li>\n\n\n\n<li><strong>Oncologie.<\/strong> Pour interrompre l\u2019approvisionnement sanguin des tumeurs (par exemple, fibromes ut\u00e9rins, certaines tumeurs h\u00e9patiques), entra\u00eenant leur r\u00e9duction. Souvent combin\u00e9e \u00e0 l\u2019injection de chimioth\u00e9rapiques (chimioembolisation).<\/li>\n\n\n\n<li><strong>M\u00e9decine d\u2019urgence.<\/strong> Pour arr\u00eater rapidement des h\u00e9morragies internes graves (gastro-intestinales, post-traumatiques, post-partum).<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">La proc\u00e9dure permet d\u2019\u00e9viter les incisions importantes, r\u00e9duit la dur\u00e9e d\u2019hospitalisation et acc\u00e9l\u00e8re la r\u00e9cup\u00e9ration. Cependant, elle comporte des risques, tels que l\u2019occlusion non intentionnelle de vaisseaux sains (embolisation non cibl\u00e9e) et le d\u00e9veloppement d\u2019un syndrome post-embolisation (douleur, fi\u00e8vre).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1227","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Embolisation : d\u00e9finition m\u00e9dicale et description | Voka Wiki<\/title>\n<meta name=\"description\" content=\"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embolisation\" \/>\n<meta property=\"og:description\" content=\"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T09:32:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/embolisation\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/embolisation\\\/\",\"name\":\"Embolisation : d\u00e9finition m\u00e9dicale et description | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"datePublished\":\"2025-09-08T08:43:37+00:00\",\"dateModified\":\"2025-10-13T09:32:31+00:00\",\"description\":\"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/embolisation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/embolisation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/embolisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossaire\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Embolisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Embolisation : d\u00e9finition m\u00e9dicale et description | Voka Wiki","description":"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Embolisation","og_description":"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.","og_url":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2025-10-13T09:32:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/","url":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/","name":"Embolisation : d\u00e9finition m\u00e9dicale et description | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"datePublished":"2025-09-08T08:43:37+00:00","dateModified":"2025-10-13T09:32:31+00:00","description":"L\u2019embolisation est une proc\u00e9dure endovasculaire mini-invasive consistant en l\u2019occlusion cibl\u00e9e d\u2019un vaisseau sanguin par l\u2019introduction de mat\u00e9riaux sp\u00e9cifiques, appel\u00e9s emboles, dans sa lumi\u00e8re.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/glossaire\/embolisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossaire","item":"https:\/\/wiki.voka.io\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Embolisation"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item\/1227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=1227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}