{"id":1421,"date":"2025-10-15T13:03:17","date_gmt":"2025-10-15T10:03:17","guid":{"rendered":"https:\/\/wiki.voka.io\/diseases\/uncategorized\/papillome-intracanalaire\/"},"modified":"2026-05-20T14:59:12","modified_gmt":"2026-05-20T11:59:12","slug":"papillome-intracanalaire","status":"publish","type":"diseases_post","link":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/","title":{"rendered":"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement."},"content":{"rendered":"<p><?xml encoding=\"UTF-8\" ?><\/p>\n<p class=\"wp-block-paragraph\">Le papillome intracanalaire est une masse b\u00e9nigne situ\u00e9e dans les canaux mammaires, qui se d\u00e9veloppe \u00e0 la suite d\u2019une prolif\u00e9ration anormale des cellules \u00e9pith\u00e9liales. <\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp\" alt=\"Papillome intracanalaire\"><figcaption class=\"wp-element-caption\">Papillome intracanalaire\u00a0: <a href=\"https:\/\/catalog.voka.io\/en\/models\/436c862c-ea12-40ad-b117-1cf8ef5cd7e1\/fc0e14a5-fb7d-4a87-a1a8-567305298de6\/03961573-ea89-4f91-98e6-1eb916cfe4bf\/695cbf99-bdc4-42b0-8a83-f0ab197d58e0\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">mod\u00e8le 3D<\/a><\/figcaption><\/figure>\n<figure class=\"wp-block-video\" id=\"animation-3d-papillome-intracanalaire\"><video controls><source data-src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/intraductal-papilloma.webm\" type=\"video\/webm\"><\/source><\/video><figcaption class=\"wp-element-caption\">Animation 3D\u00a0: papillome intracanalaire<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Les papillomes intracanalaire peuvent \u00eatre isol\u00e9s ou multiples et situ\u00e9s dans n\u2019importe quel quadrant du sein, mais ils sont le plus souvent localis\u00e9s au centre, derri\u00e8re le mamelon, et touchent le canal central.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Facteurs de risque de d\u00e9veloppement d\u2019un papillome intracanalaire<\/strong>\u00a0:<\/p>\n<ul class=\"wp-block-list\">\n<li>D\u00e9s\u00e9quilibre hormonal\u00a0;<\/li>\n<li>Maladies endocriniennes associ\u00e9es (ob\u00e9sit\u00e9, diab\u00e8te sucr\u00e9, troubles thyro\u00efdiens)\u00a0;<\/li>\n<li>Prise de contraceptifs oraux\u00a0;<\/li>\n<li>Traitement hormonal substitutif \u00e0 base d\u2019agents contenant des \u0153strog\u00e8nes\u00a0;<\/li>\n<li>Pr\u00e9disposition h\u00e9r\u00e9ditaire.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\" id=\"etiologie-et-pathogenese-du-papillome-intracanalaire\">\u00c9tiologie et pathogen\u00e8se du papillome intracanalaire<\/h2>\n<p class=\"wp-block-paragraph\">Le d\u00e9veloppement du papillome intracanalaire repose sur un d\u00e9s\u00e9quilibre hormonal, \u00e0 savoir une sensibilit\u00e9 accrue du tissu mammaire aux \u0153strog\u00e8nes et leur hyperproduction. <\/p>\n<p class=\"wp-block-paragraph\">L\u2019hyper\u0153strog\u00e9nie d\u00e9clenche la prolif\u00e9ration des cellules \u00e9pith\u00e9liales des canaux mammaires, entra\u00eenant une hyperplasie du tissu mammaire et une dilatation des canaux. \u00c0 la suite de ces processus, des excroissances papillaires se forment dans la lumi\u00e8re du canal, qui constituent des papillomes intracanalaire. <\/p>\n<h2 class=\"wp-block-heading\" id=\"presentation-morphologique\">Pr\u00e9sentation morphologique<\/h2>\n<p class=\"wp-block-paragraph\">Le papillome intracanalaire peut \u00eatre central (g\u00e9n\u00e9ralement solitaire et de grande taille) ou p\u00e9riph\u00e9rique (de petite taille, pouvant \u00eatre multiple). Sur le plan histologique, il se caract\u00e9rise par la pr\u00e9sence d\u2019une tige fibrovasculaire recouverte de cellules \u00e9pith\u00e9liales et myo\u00e9pith\u00e9liales (papilles v\u00e9ritables). <\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/1-intraductal-papilloma.webp\" alt=\"Pr\u00e9sentation morphologique du papillome intracanalaire\"><figcaption class=\"wp-element-caption\">Pr\u00e9sentation morphologique du papillome intracanalaire. Source\u00a0: <em>Webpathology. Papillome intracanalaire (Intraductal Papilloma)<\/em> [<a href=\"https:\/\/www.webpathology.com\/images\/breast\/benign-prolif-lesions\/intraductal-papilloma\/33430\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">8<\/a>]<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Le papillome intracanalaire peut s\u2019\u00e9roder et se scl\u00e9roser, mais une prolif\u00e9ration atypique, une m\u00e9taplasie squameuse ou apocrine avec malignisation ult\u00e9rieure et d\u00e9veloppement d\u2019un cancer du sein canalaire est \u00e9galement possible.<\/p>\n<figure class=\"wp-block-video\" id=\"animation-3d-papillome-intracanalaire-avec-atypie\"><video controls><source data-src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/intraductal-papilloma-with-atypia.webm\" type=\"video\/webm\"><\/source><\/video><figcaption class=\"wp-element-caption\">Animation 3D\u00a0: papillome intracanalaire avec atypie<\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\" id=\"presentation-clinique\">Pr\u00e9sentation clinique<\/h2>\n<p class=\"wp-block-paragraph\">Les manifestations cliniques du papillome intracanalaire d\u00e9pendent de sa taille et de sa localisation. <\/p>\n<p class=\"wp-block-paragraph\">Les papillomes intracanalaires p\u00e9riph\u00e9riques sont g\u00e9n\u00e9ralement asymptomatiques et d\u00e9tect\u00e9s par \u00e9chographie de d\u00e9pistage.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Les papillomes intracanalaires centraux<\/strong> se caract\u00e9risent par les <strong>sympt\u00f4mes<\/strong> suivants\u00a0:<\/p>\n<ul class=\"wp-block-list\">\n<li>Un \u00e9coulement mammaire jaun\u00e2tre-transparent \u00e0 rouge-brun (sanguinolent) est le sympt\u00f4me le plus courant\u00a0;<\/li>\n<li>Pr\u00e9sence d\u2019une masse palpable dans la r\u00e9gion ar\u00e9olaire derri\u00e8re le mamelon.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\" id=\"diagnostic-du-papillome-intracanalaire\">Diagnostic du papillome intracanalaire<\/h2>\n<ol class=\"wp-block-list\">\n<li>Ant\u00e9c\u00e9dents m\u00e9dicaux, examen et palpation des seins\u00a0;<\/li>\n<li>\u00c9chographie mammaire et ganglions lymphatiques p\u00e9riph\u00e9riques\u00a0: une masse faisant saillie dans la lumi\u00e8re du canal ou de la cavit\u00e9 kystique est visualis\u00e9e\u00a0;<\/li>\n<li>La mammographie est dans la plupart des cas peu informative et est utilis\u00e9e comme m\u00e9thode de clarification du diagnostic en cas de suspicion de cancer du sein canalaire. Sur le plan radiologique, un papillome intracanalaire peut \u00eatre d\u00e9fini comme une masse arrondie aux contours nets et r\u00e9guliers, similaire \u00e0 un kyste, mais de densit\u00e9 plus \u00e9lev\u00e9e ;<\/li>\n<li>La ductographie est utilis\u00e9e pour clarifier le diagnostic. Sur les radiographies, apr\u00e8s injection d\u2019un produit de contraste, on observe une dilatation et une d\u00e9formation du canal, des irr\u00e9gularit\u00e9s des contours avec pr\u00e9sence de formations contrast\u00e9es et un d\u00e9faut de remplissage (perturbation du sch\u00e9ma de rehaussement du contraste)\u00a0;<\/li>\n<li>L\u2019<span class=\"glossary-term\" data-title=\"IRM (imagerie par r\u00e9sonance magn\u00e9tique)\" data-tooltip=\"L&#039;imagerie par r\u00e9sonance magn\u00e9tique (IRM) est une technique moderne et non invasive de radiodiagnostic qui permet d&#039;obtenir des images en coupe des organes et des tissus internes. Cet examen repose sur le ph\u00e9nom\u00e8ne de r\u00e9sonance magn\u00e9tique nucl\u00e9aire. Le principal avantage de l&#039;IRM est l&#039;absence de rayonnements ionisants (radiation).\" data-link=\"https:\/\/wiki.voka.io\/fr\/glossaire\/irm\/\">IRM<\/span> est utilis\u00e9e pour clarifier le diagnostic. Les papillomes intracanalaire se caract\u00e9risent par la pr\u00e9sence d\u2019une masse arrondie bien d\u00e9finie \u00e0 l\u2019IRM, isointense ou l\u00e9g\u00e8rement hypointense en mode T1, et accumulant bien le contraste en mode T2\u00a0;<\/li>\n<li>Examen cytologique des s\u00e9cr\u00e9tions mammaires\u00a0;<\/li>\n<li>Biopsie par aspiration \u00e0 l\u2019aiguille fine de la tumeur\u00a0;<\/li>\n<li>Biopsie \u00e0 l\u2019aiguille de la tumeur.<\/li>\n<\/ol>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/2-intraductal-papilloma-on-ultrasound-image.webp\" alt=\"Papillome intracanalaire sur image \u00e9chographique\"><figcaption class=\"wp-element-caption\">Papillome intracanalaire sur image \u00e9chographique. Auteur\u00a0: Bruno Di Muzio. Source\u00a0: <em>Radiopaedia<\/em> [<a href=\"https:\/\/radiopaedia.org\/cases\/intraductal-papilloma-of-breast\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">11<\/a>]<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3-mammogram-of-left-breast-in-two-projections-intraductal-papilloma.webp\" alt=\"Mammographie du sein gauche en deux projections&nbsp;: papillome intracanalaire\"><figcaption class=\"wp-element-caption\">Mammographie du sein gauche en deux projections\u00a0: papillome intracanalaire. Auteur\u00a0: Ammar Ashraf. Source\u00a0: <em>Radiopaedia<\/em> [<a href=\"https:\/\/radiopaedia.org\/cases\/intraductal-papilloma-of-breast-2\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">11<\/a>]<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Vous pouvez voir ci-dessous des radiographies et des images IRM illustrant un papillome intracanalaire. Auteurs\u00a0: Mohammad Taghi Niknejad, Bahman Rasuli. Source\u00a0: <em>Radiopaedia<\/em> [<a href=\"https:\/\/radiopaedia.org\/cases\/intraductal-papilloma-breast-mri\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">11<\/a>]:<\/p>\n<div class=\"carousel-block\">\n<div class=\"swiper carousel-swiper carousel-swiper-block_6a5750838eada\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide image-carousel-slide\"><img decoding=\"async\" class=\"carousel-image\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/ductography-of-right-breast.webp\" alt=\"Ductographie du sein droit\u00a0: un d\u00e9faut de remplissage typique d'un papillome intracanalaire est d\u00e9tect\u00e9 sur la radiographie. \"><span class=\"small-text-article text-main-text-color\">Ductographie du sein droit\u00a0: un d\u00e9faut de remplissage typique d\u2019un papillome intracanalaire est d\u00e9tect\u00e9 sur la radiographie. Auteur\u00a0: Mohammad Taghi Niknejad<\/span><\/div>\n<div class=\"swiper-slide image-carousel-slide\"><img decoding=\"async\" class=\"carousel-image\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/mommo-picture-3.webp\" alt=\" Image IRM d'un papillome intracanalaire en mode pond\u00e9r\u00e9 T2 avec suppression des graisses. \"><span class=\"small-text-article text-main-text-color\"> Image IRM d\u2019un papillome intracanalaire en mode pond\u00e9r\u00e9 T2 avec suppression des graisses. Auteur\u00a0: Bahman Rasuli<\/span><\/div>\n<div class=\"swiper-slide image-carousel-slide\"><img decoding=\"async\" class=\"carousel-image\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/mammo-picture-4.webp\" alt=\"Image IRM d'un papillome intracanalaire en mode pond\u00e9r\u00e9 T1. IRM pour papillome intracanalaire. \"><span class=\"small-text-article text-main-text-color\">Image IRM d\u2019un papillome intracanalaire en mode pond\u00e9r\u00e9 T1. IRM pour papillome intracanalaire. Auteur\u00a0: Bahman Rasuli<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-article-carousel__controls\">\n<div class=\"swiper-article-carousel__pagination-container swiper-article-carousel__pagination-container-block_6a5750838eada\"><\/div>\n<div class=\"swiper-article-carousel__arrows\"><button class=\"swiper__arrow swiper__arrow--prev carousel-swiper-button-prev swiper__arrow swiper__arrow--prev carousel-swiper-button-prev-block_6a5750838eada\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewbox=\"0 0 40 40\" fill=\"none\"><path d=\"M20 3.75C16.7861 3.75 13.6443 4.70305 10.972 6.48862C8.29969 8.27419 6.21689 10.8121 4.98696 13.7814C3.75704 16.7507 3.43524 20.018 4.06225 23.1702C4.68926 26.3224 6.23692 29.2179 8.50952 31.4905C10.7821 33.7631 13.6776 35.3107 16.8298 35.9378C19.982 36.5648 23.2493 36.243 26.2186 35.013C29.1879 33.7831 31.7258 31.7003 33.5114 29.028C35.297 26.3557 36.25 23.2139 36.25 20C36.2455 15.6916 34.5319 11.561 31.4855 8.51454C28.439 5.46806 24.3084 3.75455 20 3.75ZM23.3844 25.3656C23.5005 25.4818 23.5926 25.6196 23.6555 25.7714C23.7184 25.9231 23.7507 26.0858 23.7507 26.25C23.7507 26.4142 23.7184 26.5769 23.6555 26.7286C23.5926 26.8804 23.5005 27.0182 23.3844 27.1344C23.2682 27.2505 23.1304 27.3426 22.9786 27.4055C22.8269 27.4683 22.6643 27.5007 22.5 27.5007C22.3358 27.5007 22.1731 27.4683 22.0214 27.4055C21.8696 27.3426 21.7318 27.2505 21.6156 27.1344L15.3656 20.8844C15.2494 20.7683 15.1572 20.6304 15.0943 20.4787C15.0314 20.3269 14.999 20.1643 14.999 20C14.999 19.8357 15.0314 19.6731 15.0943 19.5213C15.1572 19.3696 15.2494 19.2317 15.3656 19.1156L21.6156 12.8656C21.7318 12.7495 21.8696 12.6574 22.0214 12.5945C22.1731 12.5317 22.3358 12.4993 22.5 12.4993C22.6643 12.4993 22.8269 12.5317 22.9786 12.5945C23.1304 12.6574 23.2682 12.7495 23.3844 12.8656C23.5005 12.9818 23.5926 13.1196 23.6555 13.2714C23.7184 13.4231 23.7507 13.5858 23.7507 13.75C23.7507 13.9142 23.7184 14.0769 23.6555 14.2286C23.5926 14.3804 23.5005 14.5182 23.3844 14.6344L18.0172 20L23.3844 25.3656Z\" fill=\"#B5C0CD\"><\/path><\/svg><\/button><button class=\"swiper__arrow swiper__arrow--next carousel-swiper-button-next swiper__arrow swiper__arrow--next carousel-swiper-button-next-block_6a5750838eada\" tabindex=\"0\" aria-label=\"Next slide\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewbox=\"0 0 40 40\" fill=\"none\"><path d=\"M20 3.75C16.7861 3.75 13.6443 4.70305 10.972 6.48862C8.29969 8.27419 6.21689 10.8121 4.98696 13.7814C3.75704 16.7507 3.43524 20.018 4.06225 23.1702C4.68926 26.3224 6.23692 29.2179 8.50952 31.4905C10.7821 33.7631 13.6776 35.3107 16.8298 35.9378C19.982 36.5648 23.2493 36.243 26.2186 35.013C29.1879 33.7831 31.7258 31.7003 33.5114 29.028C35.297 26.3557 36.25 23.2139 36.25 20C36.2455 15.6916 34.5319 11.561 31.4855 8.51454C28.439 5.46806 24.3084 3.75455 20 3.75ZM23.3844 25.3656C23.5005 25.4818 23.5926 25.6196 23.6555 25.7714C23.7184 25.9231 23.7507 26.0858 23.7507 26.25C23.7507 26.4142 23.7184 26.5769 23.6555 26.7286C23.5926 26.8804 23.5005 27.0182 23.3844 27.1344C23.2682 27.2505 23.1304 27.3426 22.9786 27.4055C22.8269 27.4683 22.6643 27.5007 22.5 27.5007C22.3358 27.5007 22.1731 27.4683 22.0214 27.4055C21.8696 27.3426 21.7318 27.2505 21.6156 27.1344L15.3656 20.8844C15.2494 20.7683 15.1572 20.6304 15.0943 20.4787C15.0314 20.3269 14.999 20.1643 14.999 20C14.999 19.8357 15.0314 19.6731 15.0943 19.5213C15.1572 19.3696 15.2494 19.2317 15.3656 19.1156L21.6156 12.8656C21.7318 12.7495 21.8696 12.6574 22.0214 12.5945C22.1731 12.5317 22.3358 12.4993 22.5 12.4993C22.6643 12.4993 22.8269 12.5317 22.9786 12.5945C23.1304 12.6574 23.2682 12.7495 23.3844 12.8656C23.5005 12.9818 23.5926 13.1196 23.6555 13.2714C23.7184 13.4231 23.7507 13.5858 23.7507 13.75C23.7507 13.9142 23.7184 14.0769 23.6555 14.2286C23.5926 14.3804 23.5005 14.5182 23.3844 14.6344L18.0172 20L23.3844 25.3656Z\" fill=\"#B5C0CD\"><\/path><\/svg><\/button><\/div>\n<\/div>\n<\/div>\n<p><script defer>\n    document.addEventListener('DOMContentLoaded', function() {\n        const imagesCarouselSwiper = new Swiper('.carousel-swiper-block_6a5750838eada', {\n            slidesPerView: 1,\n            spaceBetween: 20,\n            loop: true,\n            pagination: {\n                el: '.swiper-article-carousel__pagination-container-block_6a5750838eada',\n                clickable: true,\n            },\n            navigation: {\n                nextEl: '.carousel-swiper-button-next-block_6a5750838eada',\n                prevEl: '.carousel-swiper-button-prev-block_6a5750838eada',\n            },\n        })\n    })\n<\/script><\/p>\n<div class=\"social-banner-block\">\n<div class=\"social-banner-content\">\n<p class=\"h5-title text-black\">Retrouvez d\u2019autres contenus scientifiquement exacts sur nos m\u00e9dias sociaux<\/p>\n<p><span class=\"social-banner-text text-grey\">Abonnez-vous et ne manquez pas les derni\u00e8res ressources<\/span><\/p>\n<div class=\"social-links-wrapper\"><a class=\"social-icon-link\" href=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/facebook.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.instagram.com\/voka.io\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/insta.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.linkedin.com\/company\/voka-io\/posts\/?feedView=all\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/linkedin.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.youtube.com\/@vokaio\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/youtube.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.pinterest.com\/voka3danatomyandpathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/pinterest.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.tiktok.com\/@voka.io\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/tiktok.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/discord.gg\/7ejUpq8DRR\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/discord.svg\" alt=\"social link\"><\/a><\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"social-banner-image\" loading=\"lazy\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/social-media-banner-mobile-image.webp\" alt=\"Banner background\"><\/div>\n<h2 class=\"wp-block-heading\" id=\"traitement-du-papillome-intracanalaire\">Traitement du papillome intracanalaire<\/h2>\n<p class=\"wp-block-paragraph\">Le papillome intracanalaire doit \u00eatre trait\u00e9 chirurgicalement en raison du risque \u00e9lev\u00e9 de malignisation. Une r\u00e9section sectorielle du sein (lumpectomie) suivie d\u2019un examen histologique du tissu pr\u00e9lev\u00e9 est indiqu\u00e9e.<\/p>\n<div>\n<h2 class=\"faq-title h2-article\" id=\"faq\">FAQ<\/h2>\n<div class=\"faq-section\">\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">1. Quelles sont les causes et les facteurs de risque du papillome intracanalaire\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">La cause principale est un d\u00e9s\u00e9quilibre hormonal, \u00e0 savoir une hyper\u0153strog\u00e9nie (augmentation du taux d\u2019\u0153strog\u00e8nes), qui d\u00e9clenche une prolif\u00e9ration anormale des cellules \u00e9pith\u00e9liales dans les canaux. Les principaux facteurs de risque comprennent toute affection associ\u00e9e \u00e0 ce d\u00e9s\u00e9quilibre\u00a0: maladies endocriniennes (ob\u00e9sit\u00e9, diab\u00e8te sucr\u00e9), prise de contraceptifs oraux ou de traitements hormonaux substitutifs, et pr\u00e9disposition h\u00e9r\u00e9ditaire.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">2. Quels sont les principaux sympt\u00f4mes du papillome intracanalaire\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">La pr\u00e9sentation clinique d\u00e9pend de la localisation. Les papillomes p\u00e9riph\u00e9riques sont souvent asymptomatiques. Pour les papillomes centraux situ\u00e9s pr\u00e8s du mamelon, le sympt\u00f4me le plus courant est un \u00e9coulement mammaire. Les \u00e9coulements peuvent \u00eatre de couleur jaun\u00e2tre-transparente \u00e0 sanglante (rouge-brun). Plus rarement, une petite masse dans la r\u00e9gion de l\u2019ar\u00e9ole peut \u00eatre palpable.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">3. Le papillome intracanalaire est-il consid\u00e9r\u00e9 comme un cancer et quel est le risque de malignisation\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Non, le papillome intracanalaire lui-m\u00eame est une masse b\u00e9nigne. Cependant, il est consid\u00e9r\u00e9 comme une l\u00e9sion pr\u00e9canc\u00e9reuse ou, plus pr\u00e9cis\u00e9ment, comme une masse pr\u00e9sentant un risque accru de transformation maligne. Ses cellules peuvent d\u00e9velopper une prolif\u00e9ration atypique, pr\u00e9curseur du carcinome canalaire in situ (CCIS). C\u2019est en raison de ce risque de malignisation que la strat\u00e9gie de prise en charge de ces patientes est chirurgicale.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">4. Quel traitement est indiqu\u00e9 pour le papillome intracanalaire\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Le papillome intracanalaire est soumis \u00e0 un traitement chirurgical obligatoire. Une th\u00e9rapie non chirurgicale et une strat\u00e9gie d\u2019observation ne sont pas indiqu\u00e9es en raison du risque de malignisation. La chirurgie standard consiste en une r\u00e9section sectorielle du sein (lumpectomie)\u00a0: excision du canal avec le papillome dans les tissus sains. Le mat\u00e9riel pr\u00e9lev\u00e9 est n\u00e9cessairement envoy\u00e9 pour examen histologique afin d\u2019exclure un cancer.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">5. Un papillome intracanalaire peut-il dispara\u00eetre ou s\u2019estomper spontan\u00e9ment sans traitement\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Th\u00e9oriquement, le papillome peut subir une n\u00e9crose spontan\u00e9e et une scl\u00e9rose (remplacement par du tissu cicatriciel). Cependant, \u00e9tant donn\u00e9 que tout papillome peut cacher un foyer d\u2019atypie ou un cancer d\u00e9j\u00e0 d\u00e9velopp\u00e9, la strat\u00e9gie d\u2019attente vigilante n\u2019est pas appliqu\u00e9e. Il est cliniquement injustifi\u00e9 et dangereux de compter sur la disparition spontan\u00e9e de la masse. Un papillome intracanalaire diagnostiqu\u00e9 est une indication directe pour une intervention chirurgicale.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">6. Quel est le pronostic d\u2019un papillome intracanalaire apr\u00e8s traitement\u00a0?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Apr\u00e8s ablation chirurgicale compl\u00e8te, le pronostic est g\u00e9n\u00e9ralement excellent. Si les r\u00e9sultats de l\u2019\u00e9tude histologique ne montrent aucune atypie ou signe de cancer dans le mat\u00e9riel retir\u00e9, la patiente est consid\u00e9r\u00e9e comme en bonne sant\u00e9. Cependant, le fait d\u2019avoir des ant\u00e9c\u00e9dents de papillome peut l\u00e9g\u00e8rement augmenter le risque global de d\u00e9velopper un cancer du sein \u00e0 l\u2019avenir, ce qui n\u00e9cessite un suivi r\u00e9gulier par un mammologue.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-block sources-list-hidden\" id=\"references\">\n<div class=\"sources-list-content\">\n<div class=\"sources-list-title\">\n<p class=\"small-text-bold text-black sources-list-title-text\">R\u00e9f\u00e9rences<\/p>\n<div class=\"sources-expand-button-wrapper-mobile\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-items\">\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">1.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>VOKA 3D Anatomy & Pathology \u2013 Complete Anatomy and Pathology 3D Atlas [Internet] [VOKA 3D Anatomie et Pathologie \u2013 Atlas 3D complet d\u2019anatomie et de pathologie [Internet]. VOKA 3D Anatomy & Pathology (VOKA 3D Anatomie et Pathologie). <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/catalog.voka.io\/<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">2.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Anisimov AV. BI-RADS system for ultrasound: description, classification, illustrations [Internet]. Moscow: Medison.ru. [En russe.] <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/www.medison.ru\/si\/art434.htm <\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">3.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Sencha AN. Ultrasound examination of the mammary glands. Step by step. From simple to complex. 2\u00e8me \u00e9d. Moscou\u00a0: MEDpress-inform; 2019. 176 p. [En russe.] <\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">4.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Sencha AN, Bikeev YV. Ultrasound examination of the mammary glands. Atlas. Moscou\u00a0: MEDpress-inform; 2016. 160 p. [En russe.]<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">5.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Ternovoy SK, Abduraimov AB. Radiological mammology. Moscow: GEOTAR-Media; 2007. 128 p. [En russe.] <\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">6.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>PathologyOutlines.com. Pathology Outlines [Internet]. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/www.pathologyoutlines.com<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">7.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Leithner D, Wengert GJ, Helbich TH, Thakur S, Ochoa-Albiztegui RE, Morris EA, et al. Clinical role of breast MRI now and going forward [Internet]. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/www.clinicalradiologyonline.net\/article\/S0009-9260(17)30521-4\/fulltext <\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">8.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>WebPathology. Intraductal papilloma [Internet]. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/www.webpathology.com\/<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">9.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Oksanchuk EA, Meskikh EV, Sherstneva TV, Kleshneva VO, Ershtein MA. Possibilities of the radiological method in the diagnosis of intraductal papilloma. Tumors of Female Reproductive System. 2021;17(1):32-40. [En russe.] doi: 10.17650\/1994-4098-2021-17-1-32-40.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">10.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Li A, Kirk L. Intraductal papilloma [Internet]. StatPearls \u2013 NCBI Bookshelf. 2022. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse\u00a0: https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK519539\/<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">11.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Radiopaedia.org [Internet]. Radiopaedia. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible \u00e0 l\u2019adresse suivante\u00a0: https:\/\/radiopaedia.org\/<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-expand-button-wrapper\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le papillome intracanalaire est une masse b\u00e9nigne situ\u00e9e dans les canaux mammaires, qui se d\u00e9veloppe \u00e0 la suite d&rsquo;une prolif\u00e9ration anormale des cellules \u00e9pith\u00e9liales. Les papillomes intracanalaire peuvent \u00eatre isol\u00e9s ou multiples et situ\u00e9s dans n&rsquo;importe quel quadrant du sein, mais ils sont le plus souvent localis\u00e9s au centre, derri\u00e8re le mamelon, et touchent le [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"template":"","diseases_category":[350],"class_list":["post-1421","diseases_post","type-diseases_post","status-publish","hentry","diseases_category-oncologiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Papillome mammaire intracanalaire\u00a0: sympt\u00f4mes, causes, diagnostic et traitement.<\/title>\n<meta name=\"description\" content=\"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L&#039;\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement.\" \/>\n<meta property=\"og:description\" content=\"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L&#039;\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T11:59:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/\"},\"author\":{\"name\":\"Svetlana D.\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/person\\\/48ea681c9bd412a6c978bb9af3abb639\"},\"headline\":\"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement.\",\"datePublished\":\"2025-10-15T10:03:17+00:00\",\"dateModified\":\"2026-05-20T11:59:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/oncology\\\/intraductal-papilloma\\\/3d-model-of-ductal-carcinoma-in-situ.webp\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/\",\"name\":\"Papillome mammaire intracanalaire\u00a0: sympt\u00f4mes, causes, diagnostic et traitement.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/oncology\\\/intraductal-papilloma\\\/3d-model-of-ductal-carcinoma-in-situ.webp\",\"datePublished\":\"2025-10-15T10:03:17+00:00\",\"dateModified\":\"2026-05-20T11:59:12+00:00\",\"description\":\"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L'\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/oncology\\\/intraductal-papilloma\\\/3d-model-of-ductal-carcinoma-in-situ.webp\",\"contentUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/oncology\\\/intraductal-papilloma\\\/3d-model-of-ductal-carcinoma-in-situ.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/papillome-intraductal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oncologie\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/maladies\\\/oncologiques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/principes-de-publication\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/fr\\\/#\\\/schema\\\/person\\\/48ea681c9bd412a6c978bb9af3abb639\",\"name\":\"Svetlana D.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g\",\"caption\":\"Svetlana D.\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Papillome mammaire intracanalaire\u00a0: sympt\u00f4mes, causes, diagnostic et traitement.","description":"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L'\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/","og_locale":"fr_FR","og_type":"article","og_title":"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement.","og_description":"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L'\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.","og_url":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-05-20T11:59:12+00:00","og_image":[{"url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#article","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/"},"author":{"name":"Svetlana D.","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/person\/48ea681c9bd412a6c978bb9af3abb639"},"headline":"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement.","datePublished":"2025-10-15T10:03:17+00:00","dateModified":"2026-05-20T11:59:12+00:00","mainEntityOfPage":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/"},"wordCount":702,"publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/","url":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/","name":"Papillome mammaire intracanalaire\u00a0: sympt\u00f4mes, causes, diagnostic et traitement.","isPartOf":{"@id":"https:\/\/wiki.voka.io\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#primaryimage"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp","datePublished":"2025-10-15T10:03:17+00:00","dateModified":"2026-05-20T11:59:12+00:00","description":"Papillome intracanalaire\u00a0: pr\u00e9sentation clinique, diagnostic et strat\u00e9gie de prise en charge. L'\u00e9chographie, la mammographie, la ductographie et les indications pour le traitement chirurgical (r\u00e9section sectorielle) sont pr\u00e9sent\u00e9es.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#primaryimage","url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp","contentUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/oncology\/intraductal-papilloma\/3d-model-of-ductal-carcinoma-in-situ.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/papillome-intraductal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Oncologie","item":"https:\/\/wiki.voka.io\/fr\/maladies\/oncologiques\/"},{"@type":"ListItem","position":3,"name":"Papillome mammaire intracanalaire&nbsp;: \u00e9tiologie, pr\u00e9sentation clinique, diagnostic et traitement."}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/fr\/#website","url":"https:\/\/wiki.voka.io\/fr\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/fr\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/fr\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/fr\/principes-de-publication\/"},{"@type":"Person","@id":"https:\/\/wiki.voka.io\/fr\/#\/schema\/person\/48ea681c9bd412a6c978bb9af3abb639","name":"Svetlana D.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13c4707623dc25bf8d6f213b7571cb2f1c97033975ab8a40ec877111a042661b?s=96&d=mm&r=g","caption":"Svetlana D."}}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/diseases_post\/1421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/diseases_post"}],"about":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/types\/diseases_post"}],"author":[{"embeddable":true,"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/users\/9"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/media?parent=1421"}],"wp:term":[{"taxonomy":"diseases_category","embeddable":true,"href":"https:\/\/wiki.voka.io\/fr\/wp-json\/wp\/v2\/diseases_category?post=1421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}