{"id":2508,"date":"2026-01-29T17:19:08","date_gmt":"2026-01-29T14:19:08","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/desmineralizacion-dental\/"},"modified":"2026-03-03T11:40:50","modified_gmt":"2026-03-03T08:40:50","slug":"desmineralizacion-dental","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/","title":{"rendered":"Desmineralizaci\u00f3n de los dientes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La desmineralizaci\u00f3n de los dientes (lat\u00edn: <em>demineralisatio<\/em>) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>Etiolog\u00eda y fisiopatolog\u00eda<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En valores neutros de pH (\u22487), los procesos de desmineralizaci\u00f3n (disoluci\u00f3n de cristales del componente mineral) y remineralizaci\u00f3n (restauraci\u00f3n parcial o completa de los cristales del componente mineral) del esmalte y la dentina est\u00e1n en equilibrio.<\/p>\n\n<p class=\"wp-block-paragraph\">El proceso de desmineralizaci\u00f3n predomina cuando el pH en la superficie del diente cae por debajo de un nivel cr\u00edtico (pH=5,2\u20135,5). Los \u00e1cidos producidos por las bacterias de la biopel\u00edcula o ingeridos con alimentos disuelven los cristales de hidroxiapatita. Se forman microporos en la estructura del esmalte, lo que altera sus propiedades \u00f3pticas y conduce a una p\u00e9rdida de dureza.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Importancia cl\u00ednica<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La desmineralizaci\u00f3n inicial aparece como una mancha blanca mate en la superficie del diente, visible al secarse. En esta etapa, el proceso se considera reversible: con la eliminaci\u00f3n oportuna del factor \u00e1cido y la terapia remineralizante, el esmalte puede recuperar su densidad sin tratamiento quir\u00fargico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La desmineralizaci\u00f3n de los dientes (lat\u00edn: <em>demineralisatio<\/em>) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-2508","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Desmineralizaci\u00f3n de los dientes: definici\u00f3n m\u00e9dica y descripci\u00f3n | Voka Wiki<\/title>\n<meta name=\"description\" content=\"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desmineralizaci\u00f3n de los dientes\" \/>\n<meta property=\"og:description\" content=\"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T08:40:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/desmineralizacion-dental\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/desmineralizacion-dental\\\/\",\"name\":\"Desmineralizaci\u00f3n de los dientes: definici\u00f3n m\u00e9dica y descripci\u00f3n | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#website\"},\"datePublished\":\"2026-01-29T14:19:08+00:00\",\"dateModified\":\"2026-03-03T08:40:50+00:00\",\"description\":\"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/desmineralizacion-dental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/desmineralizacion-dental\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/desmineralizacion-dental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glosario\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/glosario\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desmineralizaci\u00f3n de los dientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/principios-de-publicacion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Desmineralizaci\u00f3n de los dientes: definici\u00f3n m\u00e9dica y descripci\u00f3n | Voka Wiki","description":"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/","og_locale":"es_ES","og_type":"article","og_title":"Desmineralizaci\u00f3n de los dientes","og_description":"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.","og_url":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-03-03T08:40:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/","url":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/","name":"Desmineralizaci\u00f3n de los dientes: definici\u00f3n m\u00e9dica y descripci\u00f3n | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/es\/#website"},"datePublished":"2026-01-29T14:19:08+00:00","dateModified":"2026-03-03T08:40:50+00:00","description":"La desmineralizaci\u00f3n de los dientes (lat\u00edn: demineralisatio) es el proceso de lixiviaci\u00f3n de sustancias inorg\u00e1nicas (calcio, f\u00f3sforo) de los tejidos duros del diente bajo la acci\u00f3n de los \u00e1cidos. Este proceso es la etapa inicial de la destrucci\u00f3n del esmalte y la formaci\u00f3n de lesiones de caries.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/es\/glosario\/desmineralizacion-dental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/es\/"},{"@type":"ListItem","position":2,"name":"Glosario","item":"https:\/\/wiki.voka.io\/es\/glosario\/"},{"@type":"ListItem","position":3,"name":"Desmineralizaci\u00f3n de los dientes"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/es\/#website","url":"https:\/\/wiki.voka.io\/es\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/es\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/es\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/es\/principios-de-publicacion\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/glossary_item\/2508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/media?parent=2508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}