{"id":3513,"date":"2026-02-12T16:09:23","date_gmt":"2026-02-12T13:09:23","guid":{"rendered":"https:\/\/wiki.voka.io\/diseases\/uncategorized\/hipoplasia-sistemica-del-esmalte\/"},"modified":"2026-03-12T12:48:53","modified_gmt":"2026-03-12T09:48:53","slug":"hipoplasia-sistemica-del-esmalte","status":"publish","type":"diseases_post","link":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/","title":{"rendered":"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento"},"content":{"rendered":"<p><?xml encoding=\"UTF-8\" ?><\/p>\n<p class=\"wp-block-paragraph\">La hipoplasia del esmalte es un defecto cuantitativo y cualitativo en el desarrollo del esmalte en dientes permanentes o primarios debido a factores que alteran la funci\u00f3n de los ameloblastos. <\/p>\n<p class=\"wp-block-paragraph\">La hipoplasia sist\u00e9mica del esmalte se refiere a defectos del desarrollo en todos los dientes o en un grupo de ellos formados durante una determinada etapa de desarrollo debido a trastornos metab\u00f3licos en el ni\u00f1o o feto.<\/p>\n<h2 class=\"wp-block-heading\" id=\"etiologia\">Etiolog\u00eda<\/h2>\n<p class=\"wp-block-paragraph\">La hipoplasia del esmalte surge de una funci\u00f3n amelobl\u00e1stica alterada durante la etapa folicular del desarrollo dental. Los factores que afectan a los ameloblastos pueden dividirse en varios grupos especificados a continuaci\u00f3n.<\/p>\n<h3 class=\"wp-block-heading\" id=\"factores-prenatales\">Factores prenatales<\/h3>\n<ul class=\"wp-block-list\">\n<li>Enfermedades y afecciones patol\u00f3gicas durante el embarazo de la madre (gestosis, rub\u00e9ola, toxoplasmosis, alcoholismo, deficiencia de vitaminas A y D, diabetes mellitus, hipoparatiroidismo, s\u00edfilis, infecci\u00f3n por citomegalovirus, enfermedades del coraz\u00f3n, ri\u00f1ones y pulmones, hipertensi\u00f3n arterial o anemia)<\/li>\n<li>Exposici\u00f3n a radiaciones ionizantes durante el embarazo<\/li>\n<li>Hipoalimentaci\u00f3n o malnutrici\u00f3n durante el embarazo<\/li>\n<li>Uso prolongado de medicamentos durante el embarazo<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\" id=\"factores-neonatales\">Factores neonatales<\/h3>\n<ul class=\"wp-block-list\">\n<li>Prematuridad o bajo peso al nacer<\/li>\n<li>Factores relacionados con el parto (trauma de nacimiento, asfixia)<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li>Hipocalcemia neonatal, lesiones t\u00f3xicas, enfermedades neurol\u00f3gicas, hiperbilirrubinemia, diarrea y v\u00f3mitos prolongados, e infecciones neonatales con fiebre alta<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\" id=\"factores-posnatales\">Factores posnatales<\/h3>\n<ul class=\"wp-block-list\">\n<li>Trastornos del metabolismo de calcio y f\u00f3sforo<\/li>\n<li>Enfermedades endocrinas (que afectan a las gl\u00e1ndulas tiroides y paratiroides)<\/li>\n<li>Infecciones agudas asociadas a fiebre<\/li>\n<li>Hipovitaminosis A, C, D o E, distrofia nutricional<\/li>\n<li>Alergia cong\u00e9nita y trastornos relacionados con el metabolismo hidrosalino<\/li>\n<li>Enfermedades del tracto digestivo<\/li>\n<li>Diarrea con s\u00edntomas t\u00f3xicos<\/li>\n<li>Ictericia hemol\u00edtica<\/li>\n<li>Fenilcetonuria, alcaptonuria<\/li>\n<li>Trastornos renales<\/li>\n<li>Defectos card\u00edacos cong\u00e9nitos<\/li>\n<li>Intoxicaci\u00f3n por mercurio<\/li>\n<li>Uso prolongado de medicamentos<\/li>\n<li>Radioterapia de las mand\u00edbulas en la infancia temprana<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">A pesar de una amplia gama de factores causales, los signos cl\u00ednicos resultantes de los defectos del desarrollo del esmalte son similares. La disminuci\u00f3n o alteraci\u00f3n de la funci\u00f3n amelobl\u00e1stica debido a influencias externas lleva a alteraciones en la construcci\u00f3n de la matriz del esmalte y su mineralizaci\u00f3n. <\/p>\n<h3 class=\"wp-block-heading\" id=\"relacion-entre-la-profundidad-y-la-ubicacion-del-defecto-con-el-periodo-de-exposicion\">Relaci\u00f3n entre la profundidad y la ubicaci\u00f3n del defecto con el per\u00edodo de exposici\u00f3n<\/h3>\n<p class=\"wp-block-paragraph\">La gravedad y la localizaci\u00f3n de los defectos del esmalte reflejan per\u00edodos de trastornos metab\u00f3licos en el organismo del ni\u00f1o que coinciden con la amelog\u00e9nesis; estos dependen de la etapa de formaci\u00f3n dental en la que act\u00faa el factor etiol\u00f3gico, as\u00ed como de la intensidad y duraci\u00f3n de su efecto.<\/p>\n<h4 class=\"wp-block-heading\" id=\"h-\u0433\u043b\u0443\u0431\u0438\u043d\u0430-\u043f\u043e\u0440\u0430\u0436\u0435\u043d\u0438\u044f\">Profundidad de la lesi\u00f3n<\/h4>\n<p class=\"wp-block-paragraph\">En la hipoplasia sist\u00e9mica del esmalte, se ve afectado un grupo de dientes formados durante el mismo periodo de desarrollo; en caso de enfermedad grave o de recurrencia frecuente en el ni\u00f1o o la madre, todas las piezas dentales pueden resultar impactadas.<\/p>\n<ul class=\"wp-block-list\">\n<li>El ancho de la zona de esmalte defectuoso depende de la duraci\u00f3n del per\u00edodo de exposici\u00f3n al factor etiol\u00f3gico.<\/li>\n<li>La profundidad del defecto refleja la intensidad de la exposici\u00f3n.<\/li>\n<li>La cantidad de defectos indica la frecuencia de trastornos metab\u00f3licos en el cuerpo, que ocurren al desarrollarse una nueva enfermedad o en la recurrencia de una previa. <\/li>\n<\/ul>\n<h4 class=\"wp-block-heading\" id=\"h-\u043b\u043e\u043a\u0430\u043b\u0438\u0437\u0430\u0446\u0438\u044f-\u043f\u043e\u0440\u0430\u0436\u0435\u043d\u0438\u044f-nbsp\">Ubicaci\u00f3n de las lesiones <\/h4>\n<p class=\"wp-block-paragraph\">La ubicaci\u00f3n de los defectos del esmalte puede indicar aproximadamente la edad a la que los ameloblastos funcionaron de manera defectuosa.<\/p>\n<figure class=\"wp-block-table table-to-cards\">\n<table class=\"has-fixed-layout\">\n<thead>\n<tr>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Grupos de dientes afectados<\/strong><\/th>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Per\u00edodo de exposici\u00f3n del factor causal<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Defectos de los dientes temporales<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Per\u00edodo intrauterino<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Defectos en los dientes permanentes en los bordes incisales de los incisivos centrales, en caninos y c\u00faspides de primeros molares, as\u00ed como en incisivos laterales de la mand\u00edbula<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">De 6 meses a 1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Defectos de los incisivos laterales maxilares<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Despu\u00e9s de 1 a\u00f1o desde el nacimiento<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Las coronas de los dientes est\u00e1n afectadas hasta el tercio gingival, as\u00ed como las superficies oclusales de los premolares y segundos molares<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Hasta los 3-4 a\u00f1os<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<p class=\"wp-block-paragraph\">Los defectos del esmalte en la hipoplasia son irreversibles, ya que el esmalte dental no puede ser remodelado, a diferencia del tejido \u00f3seo. <\/p>\n<h2 class=\"wp-block-heading\" id=\"epidemiologia\">Epidemiolog\u00eda<\/h2>\n<p class=\"wp-block-paragraph\">La epidemiolog\u00eda de la hipoplasia sist\u00e9mica del esmalte se caracteriza por una alta prevalencia global, promediando un 25,3 %, con una variabilidad geogr\u00e1fica significativa (desde ~7 % en regiones pr\u00f3speras de Europa hasta m\u00e1s del 40 % en Asia y Ocean\u00eda). <\/p>\n<p class=\"wp-block-paragraph\">Tradicionalmente, las causas clave se consideran factores biol\u00f3gicos del per\u00edodo perinatal: la prematuridad y el bajo peso al nacer pueden aumentar el riesgo de desarrollo de defectos hasta en un 60 %. <\/p>\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es necesario considerar el nivel socioecon\u00f3mico: se ha demostrado una asociaci\u00f3n estad\u00edsticamente significativa entre los bajos ingresos familiares durante la infancia del paciente y la presencia de defectos del esmalte. La etiolog\u00eda de la hipoplasia del esmalte se reconoce como estrictamente multifactorial, donde la calidad de la atenci\u00f3n m\u00e9dica puede modificar la influencia de los riesgos biol\u00f3gicos. <\/p>\n<p class=\"wp-block-paragraph\">Seg\u00fan un estudio sobre una poblaci\u00f3n europea moderna, gracias a la disponibilidad de la medicina perinatal, los factores t\u00edpicos (ces\u00e1rea, prematuridad) se compensan con \u00e9xito y no derivan en defectos del esmalte, mientras que el nivel de vida desempe\u00f1a un papel crucial. No se identificaron diferencias de g\u00e9nero significativas (hombres y mujeres se ven afectados con la misma frecuencia). Morfol\u00f3gicamente, la variante m\u00e1s habitual contin\u00faa siendo la hipoplasia en forma de surco (lineal), presente en el 93 % de los casos, y afecta con mayor frecuencia a los incisivos maxilares.<\/p>\n<h2 class=\"wp-block-heading\" id=\"clasificacion-de-la-hipoplasia-sistemica-del-esmalte\">Clasificaci\u00f3n de la hipoplasia sist\u00e9mica del esmalte<\/h2>\n<ul class=\"wp-block-list\">\n<li>Forma manchada<\/li>\n<li>Forma erosiva (con picaduras)<\/li>\n<li>Forma surcada<\/li>\n<li>Forma ondulada<\/li>\n<li>Forma en copa<\/li>\n<li>Forma mixta (combinada)<\/li>\n<li>Aplasia del esmalte<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\" id=\"anatomia-patologica\">Anatom\u00eda patol\u00f3gica<\/h2>\n<p class=\"wp-block-paragraph\">El tipo de defectos del esmalte en la hipoplasia sist\u00e9mica depende del estadio de desarrollo del esmalte cuando se produjo la exposici\u00f3n al factor etiol\u00f3gico. <\/p>\n<figure class=\"wp-block-table table-to-cards\">\n<table class=\"has-fixed-layout\">\n<thead>\n<tr>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Tipo de defectos<\/strong><\/th>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Defectos del desarrollo del esmalte<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">L\u00edneas blancas, manchas blancas opacas, crema, amarillas o marrones<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Amelog\u00e9nesis imperfecta<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Picaduras, surcos, depresiones, o grandes \u00e1reas de aplasia del esmalte<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Anomal\u00edas en la deposici\u00f3n de la matriz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<figure class=\"wp-block-video\" id=\"animacion-3d-tipos-clinicos-de-hipoplasia-sistemica-del-esmalte\"><video controls><source data-src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/clinical-types-of-systemic-enamel-hypoplasia.webm\" type=\"video\/webm\"><\/source><\/video><figcaption class=\"wp-element-caption\">Animaci\u00f3n 3D: tipos cl\u00ednicos de hipoplasia sist\u00e9mica del esmalte<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">A pesar de la variabilidad de las formas cl\u00ednicas, se pueden identificar signos comunes de hipoplasia sist\u00e9mica del esmalte:<\/p>\n<ul class=\"wp-block-list\">\n<li>Los dientes erupcionan ya con defectos.<\/li>\n<li>Los defectos suelen tener una forma relativamente regular y bordes uniformes.<\/li>\n<li>Se ven afectados m\u00faltiples dientes: presentan defectos al mismo nivel, en la misma \u00e1rea de las coronas y, generalmente, son de tama\u00f1o y forma uniformes.<\/li>\n<li>Se ve afectado un grupo de dientes del mismo per\u00edodo de desarrollo; los defectos son sim\u00e9tricos.<\/li>\n<li>Los defectos son paralelos a los bordes incisales o las superficies oclusales de los dientes, m\u00e1s a menudo en la superficie labial\/bucal y las c\u00faspides.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\" id=\"cambios-microestructurales-en-los-tejidos-duros\">Cambios microestructurales en los tejidos duros<\/h3>\n<ul class=\"wp-block-list\">\n<li>En la estructura del esmalte, se observan alteraciones tanto en el grosor como en la orientaci\u00f3n de los prismas del esmalte. <\/li>\n<li>En la estructura de la dentina de los dientes afectados en el l\u00edmite con el esmalte, los t\u00fabulos dentinarios est\u00e1n curvados y tienen una disposici\u00f3n menos regular; en algunas \u00e1reas es visible un estrechamiento y ensanchamiento de sus l\u00famenes, y los cristales de hidroxiapatita est\u00e1n dispuestos de manera m\u00e1s aleatoria y suelta. <\/li>\n<li>Tambi\u00e9n se puede observar un aumento en la formaci\u00f3n de dentina terciaria por parte de la pulpa.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\" id=\"diagnostico-de-hipoplasia-sistemica-del-esmalte\">Diagn\u00f3stico de hipoplasia sist\u00e9mica del esmalte<\/h2>\n<figure class=\"wp-block-table table-to-cards\">\n<table class=\"has-fixed-layout\">\n<thead>\n<tr>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Prueba diagn\u00f3stica<\/strong><\/th>\n<th class=\"has-text-align-center\" data-align=\"center\"><strong>Presentaci\u00f3n cl\u00ednica<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Examen visual<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Presencia de cambio localizado de color del esmalte o de su grosor<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Sondeo<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Indoloro, pero puede ser doloroso si hay \u00e1reas de aplasia del esmalte o proceso de caries asociado<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Percusi\u00f3n en dientes afectados<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Indolora<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Prueba de temperatura<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">La respuesta al est\u00edmulo de temperatura desaparece inmediatamente, o unos segundos despu\u00e9s de que cese el est\u00edmulo<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Tinci\u00f3n vital<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Las manchas en el esmalte no aceptan el azul de metileno<\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">M\u00e9todos radiol\u00f3gicos (radiograf\u00eda de contacto intraoral, radiovisiograf\u00eda, ortopantomograf\u00eda [OPG], tomograf\u00eda computadorizada de haz c\u00f3nico [CBCT])<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Se identifican radiolucencias locales con contornos claros en el \u00e1rea del esmalte en la radiograf\u00eda (si hay un defecto en el grosor del esmalte)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<h2 class=\"wp-block-heading\" id=\"manifestaciones-clinicas\">Manifestaciones cl\u00ednicas<\/h2>\n<h3 class=\"wp-block-heading\" id=\"forma-manchada\">Forma manchada<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\" alt=\"Forma manchada de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma manchada de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/a3cf8aa6-9153-41bf-b7f8-e2233e8907d6\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Los pacientes pueden quejarse de una imperfecci\u00f3n cosm\u00e9tica. En la superficie bucal de los dientes, espec\u00edficamente en la zona de las c\u00faspides o del borde incisal, se identifican manchas que aparecen sobre un esmalte intacto; presentan un aspecto blanco lechoso, con menor frecuencia amarillento o pardo, con l\u00edmites n\u00edtidos y una superficie lisa y brillante. El esmalte en el \u00e1rea afectada tiene un grosor normal. Con el tiempo, las manchas no cambian de tama\u00f1o, forma ni color. Las manchas no se ti\u00f1en con azul de metileno y no se detectan en la radiograf\u00eda. <\/p>\n<h3 class=\"wp-block-heading\" id=\"forma-erosiva-con-picaduras\">Forma erosiva (con picaduras)<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/2%20-%20erosive-pitted-systemic-enamel-hypoplasia.webp\" alt=\"Forma erosiva (con picaduras) de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma erosiva (con picaduras) de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/c3cb5e0d-937f-43d4-8882-d483cc463175\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">El paciente puede quejarse de un defecto est\u00e9tico o dolor por irritantes qu\u00edmicos o t\u00e9rmicos (poco frecuente).<\/p>\n<p class=\"wp-block-paragraph\">En la superficie del esmalte, se identifican depresiones en forma de picaduras, dispuestas horizontalmente y no conectadas entre s\u00ed. Los defectos generalmente son redondos, con un fondo liso y denso y bordes poco profundos; el esmalte est\u00e1 adelgazado en estas \u00e1reas. Las picaduras son m\u00e1s profundas en las superficies labiales\/bucales de los dientes y pueden quedar te\u00f1idas de manera consistente con pigmentos alimentarios. El sondeo de los defectos es indoloro. <\/p>\n<p class=\"wp-block-paragraph\">A veces, la forma con picaduras de hipoplasia sist\u00e9mica del esmalte puede estar asociada con caries. <\/p>\n<h3 class=\"wp-block-heading\" id=\"forma-surcada\">Forma surcada<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/5.grooved-linear-systemic-enamel-hypoplasia.webp\" alt=\"Forma surcada (lineal) de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma surcada (lineal) de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/0ba8a409-e648-4cab-adca-d154674a7711\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">El paciente se queja de un defecto est\u00e9tico, a veces de dolor por irritantes mec\u00e1nicos, qu\u00edmicos y t\u00e9rmicos y de desgaste de los dientes. <\/p>\n<p class=\"wp-block-paragraph\">Visualmente, se pueden ver depresiones en forma de surcos horizontales \u00fanicos o m\u00faltiples de diferentes profundidades y anchos en los dientes; los defectos est\u00e1n ubicados paralelos al borde incisal o a la superficie oclusal. <\/p>\n<p class=\"wp-block-paragraph\">En el fondo de los surcos, el esmalte est\u00e1 adelgazado o ausente. Cuando el esmalte se conserva parcialmente, el fondo de los defectos es denso y liso, con bordes poco profundos. Si los surcos afectan a todo el grosor del esmalte, el fondo puede ser amarillo o marr\u00f3n y tener una superficie rugosa, lo que puede ser doloroso al sondear. Si el surco est\u00e1 ubicado en el borde incisal, solo tiene una pared, lo que da la impresi\u00f3n de que un diente m\u00e1s peque\u00f1o \u201ccrece\u201d de otro. En este caso, los premolares y molares presentan c\u00faspides en forma de cono poco desarrolladas, desprovistas de esmalte, que a menudo se astillan debido al estr\u00e9s mec\u00e1nico. En el \u00e1rea de defectos profundos, pueden aparecer caries. <\/p>\n<h3 class=\"wp-block-heading\" id=\"forma-ondulada\">Forma ondulada<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/3wavy-systemic-enamel-hypoplasia.webp\" alt=\"Forma ondulada de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma ondulada de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/a89f2456-c255-417f-a805-e16c21b3c194\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Es una variante de la forma surcada de la hipoplasia sist\u00e9mica del esmalte, donde se ven m\u00faltiples surcos horizontales delgados en la corona dental, que se fusionan parcialmente entre s\u00ed para formar una superficie ondulada.<\/p>\n<h3 class=\"wp-block-heading\" id=\"forma-de-copa\">Forma de copa<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/4cup-shaped-systemic-enamel-hypoplasia.webp\" alt=\"Forma de copa de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma de copa de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/92cb9582-c073-476e-b90f-a52a363337a7\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">El paciente puede quejarse de un defecto est\u00e9tico, a veces de dolor por irritantes qu\u00edmicos o t\u00e9rmicos. Los defectos aparecen como depresiones en forma de copa, ovaladas o redondas, de tama\u00f1o y profundidad variables. <\/p>\n<p class=\"wp-block-paragraph\">El esmalte en el fondo de los defectos es delgado o est\u00e1 ausente. Si se conserva una capa delgada de esmalte, los bordes, paredes y fondo de los defectos son lisos, poco profundos y densos, mientras que en \u00e1reas sin esmalte, los tejidos son rugosos y pigmentados. Si un defecto en forma de copa est\u00e1 ubicado en el \u00e1rea del borde incisal de un diente anterior, se forma una muesca semilunar en \u00e9l. En los defectos que afectan a premolares y molares, sus c\u00faspides se adelgazan y adoptan forma de aguja, siendo propensas al desgaste y a astillarse debido al estr\u00e9s mec\u00e1nico. Los defectos profundos tambi\u00e9n pueden verse afectados por caries.<\/p>\n<h3 class=\"wp-block-heading\" id=\"forma-mixta-combinada\">Forma mixta (combinada)<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/6%20-%20mixed-systemic-enamel-hypoplasia.webp\" alt=\"Forma mixta de la hipoplasia sist\u00e9mica del esmalte\"><figcaption class=\"wp-element-caption\">Forma mixta de la hipoplasia sist\u00e9mica del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/9bb9cc07-5fbc-47ea-afaa-7d1058aa9a21\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Seg\u00fan la gravedad de los defectos, el paciente refiere una apariencia est\u00e9tica deficiente, dolor ante irritantes qu\u00edmicos y t\u00e9rmicos, desgaste dental y fracturas en las c\u00faspides. <\/p>\n<p class=\"wp-block-paragraph\">La forma mixta de hipoplasia sist\u00e9mica del esmalte representa una combinaci\u00f3n de varias formas de defectos en diferentes dientes e incluso dentro de un solo diente (combinaci\u00f3n\/alternancia de manchas, depresiones, surcos y depresiones en forma de copa). Las zonas de defectos profundos, donde el esmalte est\u00e1 completamente ausente, suelen presentar fracturas, astillamientos y desgaste; asimismo, en estas \u00e1reas puede desarrollarse caries.<\/p>\n<h3 class=\"wp-block-heading\" id=\"aplasia-del-esmalte\">Aplasia del esmalte<\/h3>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/7%20-%20enamel-aplasia.webp\" alt=\"Aplasia del esmalte\"><figcaption class=\"wp-element-caption\">Aplasia del esmalte: <a href=\"https:\/\/catalog.voka.io\/en\/models\/3ed27118-f048-4865-b4ec-042c2caa7e2f\/d71e52c8-7f5a-4179-abae-97ddefd10630\/dc6648ee-5295-4895-88ef-61cf10db331d\/b5f3da64-8c54-4235-94e5-b5a0c58cc81b\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modelo 3D<\/a><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">El paciente se queja de una apariencia est\u00e9tica deficiente y dolor por irritantes mec\u00e1nicos, t\u00e9rmicos y qu\u00edmicos, as\u00ed como de desgaste y astillado de los dientes. La aplasia del esmalte es un grado severo de hipoplasia del esmalte, caracterizado por la ausencia local de esmalte en ciertas \u00e1reas o la ausencia total de esmalte en toda la corona dental. <\/p>\n<p class=\"wp-block-paragraph\">Las \u00e1reas adelgazadas del esmalte restante pueden desgastarse con el tiempo y, en lugares con defectos profundos, pueden desarrollarse caries. <\/p>\n<div class=\"social-banner-block\">\n<div class=\"social-banner-content\">\n<p class=\"h5-title text-black\">Encuentra m\u00e1s contenido cient\u00edficamente preciso en nuestras redes sociales<\/p>\n<p><span class=\"social-banner-text text-grey\">Suscr\u00edbete y no te pierdas los \u00faltimos recursos<\/span><\/p>\n<div class=\"social-links-wrapper\"><a class=\"social-icon-link\" href=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/facebook.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.instagram.com\/voka.io\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/insta.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.linkedin.com\/company\/voka-io\/posts\/?feedView=all\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/linkedin.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.youtube.com\/@vokaio\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/youtube.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.pinterest.com\/voka3danatomyandpathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/pinterest.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.tiktok.com\/@voka.io\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/tiktok.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/discord.gg\/7ejUpq8DRR\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/discord.svg\" alt=\"social link\"><\/a><\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"social-banner-image\" loading=\"lazy\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/social-media-banner-mobile-image.webp\" alt=\"Banner background\"><\/div>\n<h2 class=\"wp-block-heading\" id=\"tratamiento\">Tratamiento<\/h2>\n<p class=\"wp-block-paragraph\">El tratamiento de la hipoplasia sist\u00e9mica del esmalte depende de la gravedad de las lesiones del esmalte.<\/p>\n<ul class=\"wp-block-list\">\n<li>En presencia de l\u00edneas y manchas, pueden aplicarse t\u00e9cnicas de remineralizaci\u00f3n, blanqueamiento y microabrasi\u00f3n. <\/li>\n<li>Para el aumento de la sensibilidad dental, se utilizan desensibilizadores seg\u00fan las indicaciones.<\/li>\n<li>Ante la presencia de defectos cavitarios, se lleva a cabo la restauraci\u00f3n directa con materiales compuestos, cementos de ion\u00f3mero de vidrio (CIV) o materiales de restauraci\u00f3n de tipo comp\u00f3mero; asimismo, los tejidos dentales duros con da\u00f1os severos pueden rehabilitarse mediante carillas est\u00e9ticas, overlays o coronas completas. Es importante se\u00f1alar que los pacientes con hipoplasia sist\u00e9mica del esmalte (excepto la forma manchada) son m\u00e1s propensos a desarrollar caries y sus complicaciones.<\/li>\n<li>En casos severos, cuando los m\u00e9todos conservadores son imposibles, se extraen los dientes afectados y se usan pr\u00f3tesis.<\/li>\n<\/ul>\n<div>\n<h2 class=\"faq-title h2-article\" id=\"preguntas-frecuentes\">Preguntas Frecuentes<\/h2>\n<div class=\"faq-section\">\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">1. \u00bfSe puede restaurar el esmalte en hipoplasia con vitaminas o pastas? <\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Desgraciadamente, no. Los defectos del esmalte en la hipoplasia son irreversibles porque el esmalte, a diferencia del tejido \u00f3seo, no se puede regenerar (remodelar). Sin embargo, en el caso de formas manchadas leves, se puede mejorar la apariencia y fortalecer la estructura del esmalte con remineralizaci\u00f3n, microabrasi\u00f3n o procedimientos de blanqueamiento. Los defectos profundos requieren restauraci\u00f3n con materiales de relleno o coronas.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">2. \u00bfC\u00f3mo se puede diferenciar la hipoplasia sist\u00e9mica de las caries tempranas? <\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Hay varias diferencias clave que permiten diferenciar la hipoplasia sist\u00e9mica de las caries tempranas. Primero, es la simetr\u00eda: en la hipoplasia sist\u00e9mica, un grupo de dientes del mismo per\u00edodo de desarrollo se ve afectado, y los defectos est\u00e1n ubicados sim\u00e9tricamente en las mismas \u00e1reas de dientes hom\u00f3nimos. Segundo, es importante el momento de la aparici\u00f3n, ya que los dientes erupcionan ya defectuosos, mientras que las caries se desarrollan solo despu\u00e9s de la erupci\u00f3n. El test de tinci\u00f3n tambi\u00e9n es informativo: las manchas en la hipoplasia no se ti\u00f1en con azul de metileno (tinci\u00f3n vital), a diferencia de los sitios de desmineralizaci\u00f3n en las caries tempranas. Finalmente, las diferencias son visibles en la superficie: en la forma manchada de hipoplasia, a menudo permanece lisa y brillante, mientras que en las caries se vuelve mate y \u00e1spera.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">3. \u00bfPuede el estado de los dientes determinar cu\u00e1ndo se desarroll\u00f3 exactamente un defecto en el cuerpo del ni\u00f1o?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">El estado de los dientes permite determinar con bastante precisi\u00f3n cu\u00e1ndo se desarroll\u00f3 exactamente un defecto en el cuerpo del ni\u00f1o, ya que funcionan como un \u201carchivo biol\u00f3gico\u201d. La ubicaci\u00f3n del defecto indica la edad espec\u00edfica a la que ocurri\u00f3 el trastorno metab\u00f3lico. De este modo, los defectos en los dientes de leche indican trastornos durante el per\u00edodo intrauterino. Si se ven afectados el borde incisal de los incisivos y las c\u00faspides de los primeros molares, esto indica la presencia de problemas ocurridos entre los 6 meses y el primer a\u00f1o de vida. Los cambios en los incisivos laterales superiores indican un fallo despu\u00e9s del primer a\u00f1o. Si se observa una afectaci\u00f3n de la corona hasta la enc\u00eda, esto indica una exposici\u00f3n prolongada a un factor negativo hasta los 3 o 4 a\u00f1os de edad.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">4. \u00bfSe asocia la hipoplasia \u00fanicamente con las condiciones m\u00e9dicas maternas durante el embarazo?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">La hipoplasia no est\u00e1 exclusivamente asociada con las condiciones m\u00e9dicas maternas durante el embarazo, ya que su etiolog\u00eda es multifactorial. Los factores provocadores se dividen en tres grupos principales. Los factores prenatales incluyen las condiciones de salud materna, la toxicidad y las deficiencias nutricionales. Los factores neonatales incluyen la prematuridad, con un riesgo de hasta un 60 %, as\u00ed como lesiones de nacimiento e incompatibilidades de Rh. Las causas postnatales se refieren a las condiciones de salud del ni\u00f1o en los primeros a\u00f1os de vida, como infecciones agudas, alergias, raquitismo o el uso de ciertos medicamentos. Adem\u00e1s, el nivel socioecon\u00f3mico bajo desempe\u00f1a un papel importante, ya que suele ser un indicador de deficiencias cr\u00f3nicas de recursos y de desnutrici\u00f3n.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">5. \u00bfPor qu\u00e9 el ni\u00f1o ha desarrollado surcos horizontales en los dientes? <\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Esta es la forma surcada de hipoplasia. La cantidad y la profundidad de los surcos indican con qu\u00e9 frecuencia y qu\u00e9 tan gravemente estuvo enfermo el ni\u00f1o (o present\u00f3 un trastorno metab\u00f3lico). La profundidad de los surcos indica la intensidad del factor negativo al que estuvo expuesto el diente. La cantidad de surcos refleja la frecuencia de las enfermedades: si la enfermedad recurre, aparecen nuevos surcos. Tales defectos requieren observaci\u00f3n y, a menudo, restauraci\u00f3n, ya que el esmalte en los surcos profundos est\u00e1 adelgazado o ausente, lo que aumenta el riesgo de caries.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-block sources-list-hidden\" id=\"referencias\">\n<div class=\"sources-list-content\">\n<div class=\"sources-list-title\">\n<p class=\"small-text-bold text-black sources-list-title-text\">Referencias<\/p>\n<div class=\"sources-expand-button-wrapper-mobile\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-items\">\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">1.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>VOKA 3D Anatomy & Pathology \u2013 Atlas 3D completo de anatom\u00eda y patolog\u00eda [Complete Anatomy and Pathology 3D Atlas] [Internet]. VOKA 3D Anatomy & Pathology.<\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/catalog.voka.io\/<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">2.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Moro C, Biehler-Gomez L, Attisano GL, Gibelli DM, Boschi F, De Angelis D, Cattaneo C. Investigaci\u00f3n de la etiolog\u00eda y la distribuci\u00f3n demogr\u00e1fica de la hipoplasia del esmalte [Investigating the etiology and demographic distribution of enamel hypoplasia]. Heritage [Internet]. 2025 Oct 3;8(10):420.<\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.3390\/heritage8100420<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">3.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>K\u00fchnisch J, Fresen KF. Prevalencia de la hipomineralizaci\u00f3n del esmalte\/hipomineralizaci\u00f3n de molares e incisivos: una revisi\u00f3n exploratoria [Prevalence of Enamel Hypomineralisation\/Molar Incisor Hypomineralisation: A Scoping Review]. Monographs in Oral Science [Internet]. 1 de enero de 2024; 32:100\u2013116. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.1159\/000538876<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">4.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Ammar N, Fresen KF, Schwendicke F, K\u00fchnisch J. Tendencias epidemiol\u00f3gicas en la hipomineralizaci\u00f3n del esmalte y la hipomineralizaci\u00f3n de molares e incisivos: una revisi\u00f3n sistem\u00e1tica y metaan\u00e1lisis [Epidemiological trends in enamel hypomineralisation and molar-incisor hypomineralisation: a systematic review and meta-analysis]. Clinical Oral Investigations [Internet]. 2025 Jun 2;29(6):327.<\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.1007\/s00784-025-06411-4<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">5.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Dehailan LA, Martinez-Mier EA. Evidencia sobre la asociaci\u00f3n de factores diet\u00e9ticos generales, factores ambientales seleccionados, m\u00e9dicos, demogr\u00e1ficos y biol\u00f3gicos con los defectos del desarrollo del esmalte, incluidas la HIM y la fluorosis dental [Evidence on the association of overall dietary factors, selected environmental, medical, demographic, and biological factors and developmental defects of enamel, including MIH and enamel fluorosis]. Frontiers in Oral Health [Internet]. 11 de diciembre de 2025; 6:1616109. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.3389\/froh.2025.1616109<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">6.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Sharma D, Ganesh M, Vellore KP, Kondamadugu S, Ali A, Bartarya T. Relaci\u00f3n de la edad gestacional y el peso al nacer con las caries infantiles tempranas y los defectos del desarrollo del esmalte en ni\u00f1os de 3 a 6 a\u00f1os: un estudio transversal [Association of gestational age and birth weight with early childhood caries and developmental defects of enamel in children aged 3\u20136 years: A cross-sectional study]. Journal of Indian Society of Pedodontics and Preventive Dentistry [Internet]. 1 de octubre de 2025;43(4):485\u2013492.<\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.4103\/jisppd.jisppd_342_25<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">7.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Palottil AS, Jeseem MT, Mohanan TVS, Sajitha PS. Prevalencia de defectos del esmalte en ni\u00f1os de 12 a 15 a\u00f1os que acuden a un centro de atenci\u00f3n terciaria: un estudio transversal [Prevalence of enamel defects in 12\u201315-year-old children visiting a tertiary care center \u2013 A cross-sectional study]. Journal of Indian Society of Pedodontics and Preventive Dentistry [Internet]. 1 de julio de 2025;43(3):334\u2013338. <\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.4103\/jisppd.jisppd_185_25<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">8.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Meena M, Aijazuddin A, Kumawat R, Saxena S, Rajput T, Jaidupally RR. Evaluaci\u00f3n del impacto de la dieta en la hipoplasia del esmalte en ni\u00f1os [Assessing the impact of diet on enamel hypoplasia in children]. Journal of Pharmacy and Bioallied Sciences [Internet]. 1 de junio de 2025; 17(Supl. 2):S1972\u2013S1974.<\/cite><\/p>\n<p><span class=\"small-text-medium text-grey\">Disponible en: https:\/\/doi.org\/10.4103\/jpbs.jpbs_1818_24<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">9.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Neville B, Neville BW, Damm DD, Allen CM, Chi AC. Patolog\u00eda oral y maxilofacial [Oral and maxillofacial pathology]. Elsevier; 2023.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">10.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Scully C, Flint S, Porter SR, Moos K, Bagan J. Enfermedades orales y maxilofaciales, cuarta edici\u00f3n [Oral and Maxillofacial Diseases, fourth edition]. CRC Press; 2010.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">11.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Regezi JA, Sciubba J, Jordan RCK. Patolog\u00eda oral: correlaciones cl\u00ednicas patol\u00f3gicas [Oral pathology: Clinical Pathologic Correlations]. Elsevier Health Sciences; 2016.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">12.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Neville BW, Damm DD, Chi AC, Allen CM. Atlas en color de enfermedades orales y maxilofaciales [Color Atlas of Oral and Maxillofacial Diseases]. Elsevier; 2018.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">13.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Prabhu SR. Handbook of Oral Pathology and Oral Medicine. John Wiley & Sons; 2021.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">14.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Scully C, Welbury R, Flaitz C, De Almeida OP. Color Atlas of Orofacial Health and Disease in Children and Adolescents: Diagnosis and Management, segunda edici\u00f3n. CRC Press; 2001.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">15.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Odell EW. Fundamentos de medicina y patolog\u00eda oral de Cawson [Cawson\u2019s Essentials of Oral Pathology and Oral Medicine]. Churchill Livingstone; 2017.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">16.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Lascaris G. Atlas en color de enfermedades orales en ni\u00f1os y adolescentes [Atlas of Oral Diseases in Children and Adolescents]. Thieme; 1999.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">17.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Ongole R, Praveen BN. Libro de texto de medicina, diagn\u00f3stico y radiolog\u00eda orales [Textbook of Oral Medicine, Oral Diagnosis and Oral Radiology]. Elsevier India; 2012.<\/cite><\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">18.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\"><cite>Ghom AG, Ghom SA. Textbook of Oral Medicine. JP Medical Ltd; 2014.<\/cite><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-expand-button-wrapper\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p class=\"wp-block-paragraph\">\n","protected":false},"excerpt":{"rendered":"<p>La hipoplasia del esmalte es un defecto cuantitativo y cualitativo en el desarrollo del esmalte en dientes permanentes o primarios debido a factores que alteran la funci\u00f3n de los ameloblastos. La hipoplasia sist\u00e9mica del esmalte se refiere a defectos del desarrollo en todos los dientes o en un grupo de ellos formados durante una determinada [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","diseases_category":[272],"class_list":["post-3513","diseases_post","type-diseases_post","status-publish","hentry","diseases_category-estomatologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deficiencia generalizada del tejido adamantino: origen, categor\u00edas y terapias<\/title>\n<meta name=\"description\" content=\"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento\" \/>\n<meta property=\"og:description\" content=\"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T09:48:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/\"},\"author\":{\"name\":\"Daria A.\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/person\\\/f861ed89bfd11f2b32e1d0b47d706882\"},\"headline\":\"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento\",\"datePublished\":\"2026-02-12T13:09:23+00:00\",\"dateModified\":\"2026-03-12T09:48:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/\"},\"wordCount\":2416,\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/dentistry\\\/systemic-enamel-hypoplasia\\\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/\",\"name\":\"Deficiencia generalizada del tejido adamantino: origen, categor\u00edas y terapias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/dentistry\\\/systemic-enamel-hypoplasia\\\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\",\"datePublished\":\"2026-02-12T13:09:23+00:00\",\"dateModified\":\"2026-03-12T09:48:53+00:00\",\"description\":\"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/dentistry\\\/systemic-enamel-hypoplasia\\\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\",\"contentUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/en\\\/dentistry\\\/systemic-enamel-hypoplasia\\\/1%20-%20spotted-systemic-enamel-hypoplasia.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/hipoplasia-sistemica-del-esmalte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estomatolog\u00eda\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/enfermedades\\\/estomatologia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/principios-de-publicacion\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/es\\\/#\\\/schema\\\/person\\\/f861ed89bfd11f2b32e1d0b47d706882\",\"name\":\"Daria A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g\",\"caption\":\"Daria A.\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deficiencia generalizada del tejido adamantino: origen, categor\u00edas y terapias","description":"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/","og_locale":"es_ES","og_type":"article","og_title":"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento","og_description":"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.","og_url":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-03-12T09:48:53+00:00","og_image":[{"url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#article","isPartOf":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/"},"author":{"name":"Daria A.","@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/person\/f861ed89bfd11f2b32e1d0b47d706882"},"headline":"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento","datePublished":"2026-02-12T13:09:23+00:00","dateModified":"2026-03-12T09:48:53+00:00","mainEntityOfPage":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/"},"wordCount":2416,"publisher":{"@id":"https:\/\/wiki.voka.io\/es\/#organization"},"image":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/","url":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/","name":"Deficiencia generalizada del tejido adamantino: origen, categor\u00edas y terapias","isPartOf":{"@id":"https:\/\/wiki.voka.io\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#primaryimage"},"image":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp","datePublished":"2026-02-12T13:09:23+00:00","dateModified":"2026-03-12T09:48:53+00:00","description":"Defectos del desarrollo del esmalte: hipoplasia sist\u00e9mica. Descripci\u00f3n de la etiolog\u00eda, formas cl\u00ednicas, diagn\u00f3stico y t\u00e9cnicas de restauraci\u00f3n est\u00e9tica para los dientes.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#primaryimage","url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp","contentUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/en\/dentistry\/systemic-enamel-hypoplasia\/1%20-%20spotted-systemic-enamel-hypoplasia.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/hipoplasia-sistemica-del-esmalte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/es\/"},{"@type":"ListItem","position":2,"name":"Estomatolog\u00eda","item":"https:\/\/wiki.voka.io\/es\/enfermedades\/estomatologia\/"},{"@type":"ListItem","position":3,"name":"Hipoplasia sist\u00e9mica del esmalte: etiolog\u00eda, clasificaci\u00f3n, presentaci\u00f3n cl\u00ednica y tratamiento"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/es\/#website","url":"https:\/\/wiki.voka.io\/es\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/es\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/es\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/es\/principios-de-publicacion\/"},{"@type":"Person","@id":"https:\/\/wiki.voka.io\/es\/#\/schema\/person\/f861ed89bfd11f2b32e1d0b47d706882","name":"Daria A.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b55036bfe0a868e0402f78b7961e614dda4c6078e861af3f1c110828a06485fc?s=96&d=mm&r=g","caption":"Daria A."}}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/diseases_post\/3513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/diseases_post"}],"about":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/types\/diseases_post"}],"author":[{"embeddable":true,"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/users\/3"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/media?parent=3513"}],"wp:term":[{"taxonomy":"diseases_category","embeddable":true,"href":"https:\/\/wiki.voka.io\/es\/wp-json\/wp\/v2\/diseases_category?post=3513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}