{"id":3454,"date":"2026-02-26T16:54:09","date_gmt":"2026-02-26T13:54:09","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/hysterektomie\/"},"modified":"2026-02-26T16:54:14","modified_gmt":"2026-02-26T13:54:14","slug":"hysterektomie","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/","title":{"rendered":"Hysterektomie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Hysterektomie (von griechisch <em>hystera<\/em> &#8211; Geb\u00e4rmutter, <em>ektom\u0113<\/em> &#8211; Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c4tiologie und Pathophysiologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Die Klassifizierung der Operation h\u00e4ngt vom Ausma\u00df der Resektion ab:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Subtotale Hysterektomie (supravaginale Amputation):<\/strong> Nur der K\u00f6rper der Geb\u00e4rmutter wird entfernt, der Geb\u00e4rmutterhals bleibt erhalten. Sie ist nur m\u00f6glich, wenn keine Anomalien am Geb\u00e4rmutterhals vorliegen und die Abstriche normal sind. <\/li>\n\n\n\n<li><strong>Totale Hysterektomie (Exstirpation):<\/strong> Die Geb\u00e4rmutter wird zusammen mit dem Geb\u00e4rmutterhals in einem St\u00fcck entfernt.<\/li>\n\n\n\n<li><strong>Radikale Hysterektomie (Operation nach Wertheim):<\/strong> Erweiterte Entfernung der Geb\u00e4rmutter, des oberen Drittels der Scheide, des Parametriums und der regionalen Lymphknoten (Krebsstandard). Der Zugang kann laparotomisch (Schnitt), laparoskopisch (Punktionen) oder vaginal (durch die Vagina, ohne Einschnitte am Bauch) erfolgen. <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Klinische Bedeutung<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Ein chirurgischer Eingriff ist angezeigt, wenn organerhaltende Ma\u00dfnahmen unwirksam oder unm\u00f6glich sind: bei symptomatischen multiplen <strong>Myomen<\/strong> von Riesengr\u00f6\u00dfe (mehr als 12-14 Wochen), diffuser knotiger <strong>Adenomyose<\/strong> mit an\u00e4mischer Blutung, atypischer Hyperplasie, Endometriumkrebs sowie bei Prolaps der Genitalien. Die Hysterektomie f\u00fchrt zu einem irreversiblen Verlust der Fortpflanzungsfunktion. Wenn die Eierst\u00f6cke erhalten bleiben, leidet der Hormonhaushalt der Frau nicht dramatisch, aber das Risiko, 3-4 Jahre fr\u00fcher in die Wechseljahre zu kommen, steigt durch die Unterbrechung der Blutversorgung der Keimdr\u00fcsen.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Hysterektomie (von griechisch <em>hystera<\/em> &#8211; Geb\u00e4rmutter, <em>ektom\u0113<\/em> &#8211; Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie. <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-3454","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hysterektomie: medizinische Definition und \u00dcberblick | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hysterektomie\" \/>\n<meta property=\"og:description\" content=\"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T13:54:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/hysterektomie\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/hysterektomie\\\/\",\"name\":\"Hysterektomie: medizinische Definition und \u00dcberblick | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\"},\"datePublished\":\"2026-02-26T13:54:09+00:00\",\"dateModified\":\"2026-02-26T13:54:14+00:00\",\"description\":\"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/hysterektomie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/hysterektomie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/hysterektomie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hysterektomie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/redaktionsrichtlinien\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hysterektomie: medizinische Definition und \u00dcberblick | Voka Wiki","description":"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/","og_locale":"de_DE","og_type":"article","og_title":"Hysterektomie","og_description":"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.","og_url":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-02-26T13:54:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/","url":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/","name":"Hysterektomie: medizinische Definition und \u00dcberblick | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/de\/#website"},"datePublished":"2026-02-26T13:54:09+00:00","dateModified":"2026-02-26T13:54:14+00:00","description":"Die Hysterektomie (von griechisch hystera - Geb\u00e4rmutter, ektom\u0113 - Entfernung) ist ein radikaler chirurgischer Eingriff, der in der Entfernung der Geb\u00e4rmutter besteht. Sie ist eine der am h\u00e4ufigsten durchgef\u00fchrten Hohlraumoperationen in der operativen Gyn\u00e4kologie.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/de\/glossar\/hysterektomie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/de\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/wiki.voka.io\/de\/glossar\/"},{"@type":"ListItem","position":3,"name":"Hysterektomie"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/de\/#website","url":"https:\/\/wiki.voka.io\/de\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/de\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/de\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/de\/redaktionsrichtlinien\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item\/3454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/media?parent=3454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}