{"id":1438,"date":"2025-09-17T16:58:14","date_gmt":"2025-09-17T13:58:14","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/karbunkel\/"},"modified":"2025-10-07T19:11:38","modified_gmt":"2025-10-07T16:11:38","slug":"karbunkel","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/","title":{"rendered":"Karbunkel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.<\/p>\n\n<p class=\"wp-block-paragraph\">Im Grunde genommen stellt ein Karbunkel eine schwerere und verbreitetere Form eines Furunkels (Eiterbeule) dar. Im Gegensatz zu einem Furunkel, der einen einzigen eitrigen Strang hat, bildet ein Karbunkel mehrere eitrig-nekrotische Herde, die zu einem einzigen Konglomerat verschmelzen.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x44D;&#x442;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;-&#x438;-&#x43F;&#x430;&#x442;&#x43E;&#x444;&#x438;&#x437;&#x438;&#x43E;&#x43B;&#x43E;&#x433;&#x438;&#x44F;\"><strong>\u00c4tiologie und Pathophysiologie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Der h\u00e4ufigste Erreger ist <em>Staphylococcus aureus<\/em>. Die Infektion dringt in mehrere benachbarte Haarfollikel ein und verursacht eine diffuse Entz\u00fcndung. Der Prozess breitet sich schnell in die Tiefe und in die Breite aus und betrifft die Dermis und das subkutane Fettgewebe.<\/p>\n\n<p class=\"wp-block-paragraph\">Pathophysiologisch ist f\u00fcr einen Karbunkel eine Thrombose der Blutgef\u00e4\u00dfe charakteristisch, die den betroffenen Bereich versorgen, was zu einer breitfl\u00e4chigen Nekrose (Absterben) des Gewebes f\u00fchrt. Im Zentrum des Infiltrats bilden sich mehrere \u00d6ffnungen, durch die ein dicker gr\u00fcnlicher Eiter austritt.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Klinische Bedeutung<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Klinisch stellt ein Karbunkel ein gro\u00dfes, dichtes, \u00e4u\u00dferst schmerzhaftes Infiltrat von purpurrot-bl\u00e4ulicher Farbe dar. Seine Entwicklung geht mit ausgepr\u00e4gten Allgemeinsymptomen einher: Fieber, Sch\u00fcttelfrost, Schw\u00e4che. Die gef\u00e4hrlichste Lokalisation ist das Gesicht (Oberlippe, Nase), da hier die Gefahr einer Ausbreitung der Infektion in die Sch\u00e4delh\u00f6hle besteht (Sinus-cavernosus-Thrombose).<\/p>\n\n<p class=\"wp-block-paragraph\">Die Behandlung eines Karbunkels erfolgt im Gegensatz zu den meisten Furunkeln fast immer chirurgisch. Sie besteht in einem breiten kreuzf\u00f6rmigen Schnitt des Infiltrats, der Entfernung des gesamten nekrotischen Gewebes und der Sicherstellung eines ausreichenden Eiterabflusses. Die Operation muss unbedingt durch eine systemische Antibiotikatherapie erg\u00e4nzt werden. Versuche, den Karbunkel selbst auszudr\u00fccken, sind aufgrund des hohen Risikos einer Ausbreitung der Infektion strengstens verboten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1438","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Karbunkel: medizinische Definition und \u00dcberblick | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karbunkel\" \/>\n<meta property=\"og:description\" content=\"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T16:11:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/karbunkel\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/karbunkel\\\/\",\"name\":\"Karbunkel: medizinische Definition und \u00dcberblick | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\"},\"datePublished\":\"2025-09-17T13:58:14+00:00\",\"dateModified\":\"2025-10-07T16:11:38+00:00\",\"description\":\"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/karbunkel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/karbunkel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/karbunkel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Karbunkel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/redaktionsrichtlinien\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Karbunkel: medizinische Definition und \u00dcberblick | Voka Wiki","description":"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/","og_locale":"de_DE","og_type":"article","og_title":"Karbunkel","og_description":"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.","og_url":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2025-10-07T16:11:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/","url":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/","name":"Karbunkel: medizinische Definition und \u00dcberblick | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/de\/#website"},"datePublished":"2025-09-17T13:58:14+00:00","dateModified":"2025-10-07T16:11:38+00:00","description":"Als Karbunkel bezeichnet man eine akute eitrig-nekrotische Entz\u00fcndung, die eine Gruppe benachbarter Haarfollikel und Talgdr\u00fcsen betrifft. Der Prozess ist durch die Bildung eines ausgedehnten und tiefen Infiltrats in der Haut und im Subkutangewebe gekennzeichnet, gefolgt von Nekrose und Gewebeabsto\u00dfung.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/de\/glossar\/karbunkel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/de\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/wiki.voka.io\/de\/glossar\/"},{"@type":"ListItem","position":3,"name":"Karbunkel"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/de\/#website","url":"https:\/\/wiki.voka.io\/de\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/de\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/de\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/de\/redaktionsrichtlinien\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item\/1438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/media?parent=1438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}