{"id":1211,"date":"2025-10-30T11:39:00","date_gmt":"2025-10-30T08:39:00","guid":{"rendered":"https:\/\/wiki.voka.io\/glossary\/%d0%b0%d0%bd%d0%b0%d0%bc%d0%bd%d0%b5%d0%b7\/"},"modified":"2025-10-30T11:39:03","modified_gmt":"2025-10-30T08:39:03","slug":"anamnese","status":"publish","type":"glossary_item","link":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/","title":{"rendered":"Anamnese"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Anamnese (griechisch <em>an\u00e1mn\u0113sis<\/em>\u00a0\u2013 Erinnerung) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten ermittelt werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.<\/p>\n\n<p class=\"wp-block-paragraph\">Es handelt sich hierbei nicht einfach um eine Zusammenstellung von Beschwerden, sondern um einen strukturierten Dialog mit dem Ziel, die Geschichte der Entwicklung pathologischer Prozesse zu rekonstruieren. Die Qualit\u00e4t der erfassten Krankengeschichte hat direkten Einfluss auf die Genauigkeit einer Verdachtsdiagnose und die Effektivit\u00e4t der gesamten nachfolgenden Untersuchung.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x441;&#x442;&#x440;&#x443;&#x43A;&#x442;&#x443;&#x440;&#x430;-&#x430;&#x43D;&#x430;&#x43C;&#x43D;&#x435;&#x437;&#x430;\"><strong>Struktur der Anamnese<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">In der klinischen Praxis werden systematisch Informationen zu Schl\u00fcsselbereichen gesammelt:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Anamnaesis morbi<\/em><\/strong> <strong>(Anamnese der Erkrankung).<\/strong> Eine eine detaillierte Chronologie der Entwicklung der aktuellen Symptome, ihrer Art, Dynamik und bisherigen Behandlung.<\/li>\n\n\n\n<li><strong><em>Anamnesis vitae<\/em><\/strong> <strong>(Anamnese der Lebensgeschichte).<\/strong> Enth\u00e4lt Informationen \u00fcber fr\u00fchere Erkrankungen, Operationen, Arbeitsbedingungen, sch\u00e4dliche Gewohnheiten und Vererbung (Familienanamnese).<\/li>\n\n\n\n<li><strong>Spezielle Anamnesetypen.<\/strong> Hierzu z\u00e4hlen allergische, gyn\u00e4kologische und epidemiologische Anamnesen, die je nach Umst\u00e4nden gezielt erhoben werden.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-&#x43A;&#x43B;&#x438;&#x43D;&#x438;&#x447;&#x435;&#x441;&#x43A;&#x43E;&#x435;-&#x437;&#x43D;&#x430;&#x447;&#x435;&#x43D;&#x438;&#x435;\"><strong>Klinische Signifikanz<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Der diagnostische Wert der Anamnese ist enorm; man nimmt an, dass sie in der allgemeinmedizinischen Praxis in 70\u201380 % der F\u00e4lle eine korrekte Diagnose erm\u00f6glicht. Dank einer kompetent erhobenen Krankengeschichte kann eine erste diagnostische Hypothese gebildet und ein gezielter Plan f\u00fcr die k\u00f6rperliche und instrumentelle Untersuchung erstellt werden.<\/p>\n\n<p class=\"wp-block-paragraph\">Zus\u00e4tzlich ist die Erhebung der Krankengeschichte entscheidend f\u00fcr den Aufbau eines vertrauensvollen Verh\u00e4ltnisses zwischen Arzt und Patient. Dies wirkt sich direkt auf die Therapietreue (Compliance) des Patienten und somit letztlich auf den Behandlungserfolg aus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1211","glossary_item","type-glossary_item","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anamnese: medizinische Definition und \u00dcberblick | Voka Wiki<\/title>\n<meta name=\"description\" content=\"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anamnese\" \/>\n<meta property=\"og:description\" content=\"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T08:39:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/anamnese\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/anamnese\\\/\",\"name\":\"Anamnese: medizinische Definition und \u00dcberblick | Voka Wiki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\"},\"datePublished\":\"2025-10-30T08:39:00+00:00\",\"dateModified\":\"2025-10-30T08:39:03+00:00\",\"description\":\"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/anamnese\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/anamnese\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/anamnese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/glossar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anamnese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/redaktionsrichtlinien\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anamnese: medizinische Definition und \u00dcberblick | Voka Wiki","description":"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/","og_locale":"de_DE","og_type":"article","og_title":"Anamnese","og_description":"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.","og_url":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2025-10-30T08:39:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/","url":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/","name":"Anamnese: medizinische Definition und \u00dcberblick | Voka Wiki","isPartOf":{"@id":"https:\/\/wiki.voka.io\/de\/#website"},"datePublished":"2025-10-30T08:39:00+00:00","dateModified":"2025-10-30T08:39:03+00:00","description":"Die Erfassung der Krankengeschichte (Anamnese) ist eine grundlegende Methode der klinischen Untersuchung, bei der durch Befragung Informationen zur Krankheit, den Lebensumst\u00e4nden und den individuellen Merkmalen eines Patienten gewonnen werden. Dies ist die wesentliche und aufschlussreichste Phase des Diagnoseverfahrens.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/de\/glossar\/anamnese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/de\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/wiki.voka.io\/de\/glossar\/"},{"@type":"ListItem","position":3,"name":"Anamnese"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/de\/#website","url":"https:\/\/wiki.voka.io\/de\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/de\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/de\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/de\/redaktionsrichtlinien\/"}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item\/1211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/glossary_item"}],"about":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/types\/glossary_item"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/media?parent=1211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}