{"id":546,"date":"2025-04-04T13:36:13","date_gmt":"2025-04-04T10:36:13","guid":{"rendered":"https:\/\/wiki.voka.io\/diseases\/uncategorized\/nasenbluten\/"},"modified":"2026-01-13T15:49:12","modified_gmt":"2026-01-13T12:49:12","slug":"nasenbluten","status":"publish","type":"diseases_post","link":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/","title":{"rendered":"Nasenbluten: Ursachen, erste Hilfe, Behandlung"},"content":{"rendered":"<p><?xml encoding=\"UTF-8\" ?><\/p>\n<p class=\"wp-block-paragraph\">Unter Nasenbluten (<em>Epistaxis<\/em>) versteht man das Austreten von Blut aus einem Blutgef\u00e4\u00df der Nasenh\u00f6hle durch die St\u00f6rung seiner Integrit\u00e4t oder Permeabilit\u00e4t. Es ist eine der h\u00e4ufigsten Blutungen.  <\/p>\n<h2 class=\"wp-block-heading\" id=\"klassifikation\">Klassifikation<\/h2>\n<figure class=\"wp-block-table table-to-cards table-accents\">\n<table class=\"has-fixed-layout\">\n<tbody>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Lokalisation<\/td>\n<td>\u2013 anteriore Blutung<br \/>\u2013 <span class=\"glossary-term\" data-title=\"Posteriores Nasenbluten\" data-tooltip=\"Posteriores Nasenbluten (Epistaxis) liegt vor, wenn die Blutungsquelle im hinteren Bereich der Nasenh\u00f6hle liegt. Anders als bei der h\u00e4ufigeren anterioren (vorderen) Epistaxis sind hintere Nasenblutungen massiver, gef\u00e4hrlicher, schwieriger zu behandeln und potentiell lebensgef\u00e4hrlich.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/posteriores-nasenbluten\/\">posteriore Blutung<\/span><\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">\u00c4tiologie<\/td>\n<td>\u2013 traumatisch<br \/>\u2013 verursacht durch lokale Prozesse<br \/>\u2013 verursacht durch h\u00e4ufige Krankheiten  <\/td>\n<\/tr>\n<tr>\n<td class=\"has-text-align-center\" data-align=\"center\">Blutverlust<\/td>\n<td>\u2013 schwache Blutung<br \/>\u2013 m\u00e4\u00dfige Blutung<br \/>\u2013 starke Blutung<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<h2 class=\"wp-block-heading\" id=\"aetiologie\">\u00c4tiologie <\/h2>\n<p class=\"wp-block-paragraph\">Nasenbluten k\u00f6nnen durch Traumata, lokale und generalisierte Faktoren ausgel\u00f6st werden. Nur noch 20 % davon gehen auf Pathologien der Nasenh\u00f6hle zur\u00fcck und ca. 80 % sind mit Allgemeinerkrankungen verbunden.  <\/p>\n<p class=\"wp-block-paragraph\"><strong>Traumatisches Nasenbluten<\/strong> ist am h\u00e4ufigsten, dazu z\u00e4hlen auch intra- und postoperative Blutungen der Nasenh\u00f6hle und des <span class=\"glossary-term\" data-title=\"Nasopharynx\" data-tooltip=\"Der Nasopharynx (lat. Pars nasalis pharyngis) ist der obere, ausschlie\u00dflich f\u00fcr die Atmung zust\u00e4ndige Abschnitt des Rachens, der einen Raum hinter der Nasenh\u00f6hle und \u00fcber dem weichen Gaumen darstellt. Oben grenzt sein Dach an die Sch\u00e4delbasis (Keilbein und Hinterhauptbein). Im Gegensatz zum Oropharynx und Laryngopharynx ist der Nasopharynx nicht am Schluckvorgang beteiligt.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/nasofarinks\/\">Nasopharynx<\/span> (Septumplastik, Conchotomie, <span class=\"glossary-term\" data-title=\"Adenotomie\" data-tooltip=\"Eine Adenotomie ist ein chirurgischer Eingriff, bei dem hypertrophe Rachenmandeln entfernt werden (adenoide Vegetation). Diese Intervention zielt darauf ab, die Nasenatmung und Drainagefunktion der Geh\u00f6rg\u00e4nge wiederherzustellen und die Quelle chronischer Infektionen im Nasopharynx zu eliminieren.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/adenotomie\/\">Adenotomie<\/span>, Sinustomie). <\/p>\n<p class=\"wp-block-paragraph\">Zu den <strong>lokalen Ursachen<\/strong>, die sich durch Epistaxis andeuten, z\u00e4hlen atrophische Prozesse in der Nasenh\u00f6hle (kommen bei \u00e4lteren Leuten sowie bei trockener Raumluft vor), die bei langem Bestehen Schleimhautulzera und <span class=\"glossary-term\" data-title=\"Perforation\" data-tooltip=\"Die Perforation (lat. perforatio &quot;Durchbohrung&quot;) ist ein pathologischer Zustand, bei dem ein durchgehender Defekt in der Wand eines Hohlorganes entsteht. Infolge der Perforation kommt es zu einer Verbindung zwischen dem Lumen dieses Organs und den angrenzenden K\u00f6rperh\u00f6hlen (Bauchh\u00f6hle, Pleurah\u00f6hle, Mediastinum) oder der Au\u00dfenumgebung.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/perforation\/\">Perforation<\/span> der Nasenscheidewand verursachen k\u00f6nnen, was Nasenblutungen weiter verschlimmert. Fremdk\u00f6rper in der Nase, mechanische Manipulation (Nasebohren), Infektionsprozesse (Rinitis, <span class=\"glossary-term\" data-title=\"Sinusitis\" data-tooltip=\"Sinusitis (vom lateinischen \u201esinus\u201c) ist eine Entz\u00fcndung der Schleimhaut einer oder mehrerer Nasennebenh\u00f6hlen. Da der Entz\u00fcndungsprozess fast immer die Schleimhaut der Nasenh\u00f6hle (Rhinitis) betrifft, wird in der modernen medizinischen Praxis ein genauerer Begriff verwendet: Rhinosinusitis.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/sinusitis\/\">Sinusitis<\/span>, virale Infektionen) besch\u00e4digen die Nasenschleimhaut und die Gef\u00e4\u00dfwand und sind auch unter den Ursachen von geringem Nasenbluten. Einer Epistaxis liegen auch lokale benigne (juveniles Angiofibrom, kapill\u00e4re bzw. kavern\u00f6s H\u00e4mangiome der Nasenh\u00f6hle, Papillome) oder maligne (Karzinom und Nasensarkom) Neubildungen der Nasenh\u00f6hle zugrunde. Sehr selten werden letzte Zeit auch lokale Erscheinungen spezifischer Erkrankungen wie Tuberkulom, Ozaena, unterschiedliche Syphilisstadien (Ulcus durum, sekund\u00e4re <span class=\"glossary-term\" data-title=\"Syphilis\" data-tooltip=\"Die Syphilis (lat. syphilis, lues) ist eine chronische systemische Geschlechtskrankheit, die durch Infektion mit Treponema pallidum hervorgerufen wird. Die Krankheit ist durch einen stufenweisen, wellenf\u00f6rmigen Verlauf gekennzeichnet, bei dem alle Organe und Systeme des K\u00f6rpers betroffen sind, vor allem die Haut, die Schleimh\u00e4ute, das Nerven-, das Herz-Kreislaufsystem und der Bewegungsapparat.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/syphilis\/\">syphilitische<\/span> Papeln, syphilitisches Gumma) diagnostiziert.   <\/p>\n<p class=\"wp-block-paragraph\"><strong>Allgemeinerkrankungen<\/strong>, die einem Nasenbluten zugrunde liegen, werden in folgende Gruppen unterteilt: Herz-Kreislauf-Erkrankungen (<span class=\"glossary-term\" data-title=\"Atherosklerose\" data-tooltip=\"Atherosklerose (von altgr. \u1f00\u03b8\u03ae\u03c1\u03b1 \u201eBrei\u201c und \u03c3\u03ba\u03bb\u03b7\u03c1\u03cc\u03c2 \u201ehart\u201c) ist eine chronische Erkrankung der Arterien vom elastischen und muskul\u00e4ren Typ, die durch die Ablagerung und Ansammlung von Lipiden (vor allem Cholesterin) in der inneren Wandschicht gekennzeichnet ist. Dadurch entstehen atherosklerotische Plaques, die das Gef\u00e4\u00dflumen verengen, die Gef\u00e4\u00dfw\u00e4nde verdichten und verformen und somit ihre Elastizit\u00e4t verringern.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/aterosklerose\/\">Atherosklerose<\/span>, Hypertonie, heredit\u00e4re h\u00e4morrhagische Teleangiektasie \u2013 Osler-Rendu-Weber-Krankheit), Lebererkrankungen (Zirrhose, Hepatitis), Erkrankungen des blutbildenden Systems (H\u00e4mophilie, Koagulopathie, Thrombozytopenie, <span class=\"glossary-term\" data-title=\"Leuk\u00e4mie\" data-tooltip=\"Als Leuk\u00e4mie, auch Leukose, bezeichnet man b\u00f6sartige (neoplastische) Erkrankungen des blutbildenden Systems. Sie sind durch eine unkontrollierte Bildung und Ansammlung abnormaler Leukozyten (wei\u00dfe Blutk\u00f6rperchen) und eine Besiedlung des Knochenmarkes gekennzeichnet.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/leukaemie\/\">Leuk\u00e4mie<\/span>, H\u00e4moblastose), Nebenwirkungen einiger Arzneimittel (NSAR, Antikoagulanzien). <\/p>\n<p class=\"wp-block-paragraph\">Getrennt sind Nasenbluten durch <strong>hormonelle Ver\u00e4nderungen<\/strong> (bei Schwangerschaft, Menopause) sowie im Zusammenhang mit Menstruationszyklus bei Frauen (vikarierende Blutungen \u2013 normale Blutung mit auftretenden, nicht genitalen Blutungen) zu betrachten. <\/p>\n<h2 class=\"wp-block-heading\" id=\"anatomie\">Anatomie <\/h2>\n<p class=\"wp-block-paragraph\">Nasenblutungen beruhen auf verschiedenen pathologischen Prozessen, die in der Nasenh\u00f6hle mit ihren Gef\u00e4\u00dfw\u00e4nden auftreten. Anatomisch gesehen ist es wichtig, die Blutungsquelle abzugrenzen, da sie die H\u00f6he des m\u00f6glichen Blutverlustes bestimmt. Eine Besonderheit der Blutversorgung der Nasenh\u00f6hle sind die zahlreichen <span class=\"glossary-term\" data-title=\"Anastomose\" data-tooltip=\"Eine Anastomose (griechisch: anast\u00f3m\u014dsis \u2013 \u00d6ffnung) ist eine nat\u00fcrlich auftretende oder chirurgisch hergestellte Verbindung zwischen hohlen anatomischen Strukturen, wie z. B. Blut- und Lymphgef\u00e4\u00dfen oder Abschnitten von Hohlorganen (z. B. dem Darm).\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/anastomose\/\">Anastomosen<\/span> zwischen den \u00c4sten der Arteria carotis interna und externa. Die <strong>vordere Blutung <\/strong>entspricht h\u00e4ufiger der <em><span style=\"text-decoration: underline;\">Kisselbach\u2019schen Zone<\/span><\/em> (ein entwickeltes Netzwerk von Blutgef\u00e4\u00dfen), die sich auf der Nasenscheidewand im Nasenvorhof befindet. Die Kisselbach-Zone wird durch den Plexus der vorderen und hinteren Gitterarterien (\u00c4ste der Arteria carotis interna), der Arteria cuneiformis palatina, der Arteria palatina major und der Arteria labialis superior (\u00c4ste der Arteria carotis externa) gebildet.     <\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp\" alt=\"Kiesselbach-Plexus\"><figcaption class=\"wp-element-caption\"><span class=\"glossary-term\" data-title=\"Kiesselbach-Plexus\" data-tooltip=\"Der Kisselbach-Plexus ist ein dichtes Netz von anastomosierenden (miteinander verbundenen) Arterien, das sich in der Nasenschleimhaut im anterior-inferioren Drittel des Nasenseptums befindet.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/kiesselbach-plexus\/\">Kiesselbach-Plexus<\/span><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Die <strong>posteriore<\/strong> Blutung entspricht einer direkten Sch\u00e4digung der<span style=\"text-decoration: underline;\"><em>an den vorderen oder hinteren Gitterarterien<\/em><\/span><em>. <\/em><\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/2-Ethmoid%20arteries%20of%20the%20nasal%20septum_arrow.webp\" alt=\"Siebbeinarterien des Nasenseptums\"><figcaption class=\"wp-element-caption\">Siebbeinarterien des Nasenseptums<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Bei Traumata, Operationen und lokalen pathologischen Prozessen kommt es zur Verletzung (Riss) der Gef\u00e4\u00dfwand in der Nasenh\u00f6hle, die mit einer Blutung einhergeht. Neubildungen der Nasenh\u00f6hle und diverse Infektionsulzera k\u00f6nnen durch ihren eigenst\u00e4ndigen Zerfall bluten. Herz-Kreislauf-Erkrankungen sind durch pathologische Ver\u00e4nderungen der Gef\u00e4\u00dfwand gekennzeichnet. Es kommt zur Endotheldystrophie, erh\u00f6hter Thrombusbildung, die die Gef\u00e4\u00dfwandnekrose und -sklerose noch weiter beeintr\u00e4chtigen, wodurch die Gef\u00e4\u00dfwand d\u00fcnn wird. Diese Prozesse k\u00f6nnen sowohl ein Durchtritt von Blutk\u00f6rperchen durch die Gef\u00e4\u00dfwand (Diapedese), als auch Gef\u00e4\u00dfwandriss in den am st\u00e4rksten verletzten Stellen mit massiver Blutung verursachen, die bei erh\u00f6htem Blutdruck st\u00e4rker wird. Bei Leber- und Bluterkrankungen ist die Gef\u00e4\u00df-Thrombozyten-H\u00e4mostase gest\u00f6rt: es kommt zum Mangel an Blutgerinnungsfaktoren, die Thrombozytenbildung und -aggregation ist gest\u00f6rt, was f\u00fcr den Bau des Gef\u00e4\u00dfwandendothels von Bedeutung ist, da die Thrombozyten u.a. anisotropische Funktion erf\u00fcllen; es kommt zum Syndrom lokaler intravasaler Gerinnung. Dies alles resultiert auch in diapedesem Durchtritt bzw. Gef\u00e4\u00dfruptur mit anschlie\u00dfender H\u00e4mostasest\u00f6rung durch verminderte Gerinnung, wodurch es zur Verl\u00e4ngerung der Blutungszeit kommt.      <\/p>\n<p class=\"wp-block-paragraph\">Epistaxis durch hormonelle Ver\u00e4nderungen bei Schwangeren kommt wegen erh\u00f6htem Progesteronspiegel zustande, der eine Gef\u00e4\u00dferweiterung nicht nur in der Plazenta, sondern auch in der Nasenh\u00f6hle sowie eine h\u00f6here Gef\u00e4\u00dfpermeabilit\u00e4t verursacht, was die Nasenschleimhaut br\u00fcchig und leicht zu verletzen macht. Die Ursache f\u00fcr vikarierende Blutungen ist bisher nicht klar, es wird eine Migration der Endometriumzellen in untypische Orte (Nasenh\u00f6hle, Thoraxh\u00f6hle, Abdomen) vermutet, die sich bei der Menstruation abschuppen und bluten. <\/p>\n<h2 class=\"wp-block-heading\" id=\"klinische-zeichen-von-nasenbluten\">Klinische Zeichen von Nasenbluten <\/h2>\n<p class=\"wp-block-paragraph\">Nasenbluten zeichnet sich durch einen Austritt von Blut aus der Nasenh\u00f6hle durch den Nasenvorhof oder den Nasopharynx aus.<\/p>\n<figure class=\"wp-block-video\" id=\"3d-animation-anteriore-nasenblutung\"><video controls><source data-src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleed-from-the-anterior-sections.webm\" type=\"video\/webm\"><\/source><\/video><figcaption class=\"wp-element-caption\">3D-Animation \u2013 anteriore Nasenblutung<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Abh\u00e4ngig vom Umfang des Blutverlustes spricht man von sp\u00e4rlicher (mehrere Milliliter), m\u00e4\u00dfiger (bis zu 200\u2013250 ml) oder starker (\u00fcber 250\u2013300 ml) Blutung. Einige Patienten k\u00f6nnen vor ihrem Ausbruch Prodrome wie Tinnitus, schwarze Punkte vor den Augen, Nasenjuckreiz aufweisen.  <\/p>\n<p class=\"wp-block-paragraph\"><strong>Sp\u00e4rliches Nasenbluten<\/strong> h\u00f6rt meist von selbst auf, ohne die Notwendigkeit einer medizinischen Versorgung. Am h\u00e4ufigsten ist es im Locus Kiesselbachi lokalisiert und entsteht durch lokale pathologische, oft atrophische Prozesse in der Nasenh\u00f6hle, dauert einige Minuten, wobei der Allgemeinzustand unbeeintr\u00e4chtigt bleibt. Das Blut ist intensiv rot und tritt \u00fcber den Nasenvorhof in Tropfen oder einem sp\u00e4rlichen Faden aus. <\/p>\n<p class=\"wp-block-paragraph\"><strong>M\u00e4\u00dfiges und starkes Nasenbluten <\/strong>zeichnet sich durch eine strahlartige Blutung, meist dunkelrot, \u00fcber den Nasenvorhof sowie an der Rachenhinterwand aus, wobei das Blut verschluckt wird und nachfolgend H\u00e4matemesis (Bluterbrechen) bzw. Mel\u00e4na (Teerstuhl) verursachen kann. Bei wesentlichem (\u00fcber 1 Liter) Blutverlust innerhalb kurzer Zeit kommen die Allgemeinsymptome des hypovol\u00e4mischen Schocks wie kalter klebriger Schwei\u00df, Tachypnoe, arterieller Druckabfall, erh\u00f6hte Herzfrequenz, Kopfschmerzen, schwarze Punkte vor den Augen, \u00dcbelkeit und Erbrechen, Bewusstseinsverlust hinzu.  <\/p>\n<p class=\"wp-block-paragraph\">Die Epistaxis als Symptom von Allgemeinerkrankungen zeichnet sich durch sp\u00e4rliche bzw. m\u00e4\u00dfige rezidivierende Blutungen aus, wobei der gesamte Blutverlust nicht genau einzusch\u00e4tzen ist und es zu einer chronischen Blutungsan\u00e4mie kommt. Bei Nasentraumata mit Fraktur des Labyrinthus ethmoidalis erfolgt eine Verletzung der vorderen und hinteren Arteriae ethmoidalis mit anschlie\u00dfender starker profuser Blutung und Entwicklung eines hypovol\u00e4mischen Schocks. <\/p>\n<p class=\"wp-block-paragraph\">Wichtig ist zu wissen, dass \u00fcber die Nase auch das Blut aus einer Lunge oder aus dem Magen-Darm-Trakt sowie aus der Paukenh\u00f6hle \u00fcber die Tuba auditiva austreten kann, was f\u00e4lschlicherweise als Nasenbluten betrachtet werden kann und die Diagnostik sowie Verordnung einer ad\u00e4quaten Therapie verschieben kann. <\/p>\n<h2 class=\"wp-block-heading\" id=\"diagnostik\"><strong>Diagnostik <\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Um die Blutungsquelle zu bestimmen, erfolgt ggf. nach der Entfernung von Blutklumpen eine <strong>Rhinopharyngoskopie<\/strong>, in einigen F\u00e4llen auch eine <strong><span class=\"glossary-term\" data-title=\"Endoskopie\" data-tooltip=\"Die Endoskopie ist eine Forschungs- und Behandlungsmethode, die es dem Arzt erm\u00f6glicht, innere Hohlr\u00e4ume und Hohlorgane mit einem speziellen Ger\u00e4t - einem Endoskop - zu untersuchen. Ein Endoskop ist ein flexibles oder starres Instrument mit einem optischen System (Kamera) und einer Lichtquelle am Ende. \" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/endoskopiye\/\">Nasenh\u00f6hlenendoskopie<\/span><\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Die <strong>Blutungsdauer<\/strong>, <strong>ausl\u00f6sende Faktoren<\/strong>, ausf\u00fchrliche <strong>Anamnese<\/strong> einschl. famili\u00e4r (Erbkrankheiten) sowie Medikationsanamnese (Antikoagulanzien, NSAR) sind zu bestimmen. <\/p>\n<p class=\"wp-block-paragraph\">Der <strong>arterielle Blutdruck<\/strong> sowie die <strong>Herzfrequenz<\/strong> sind zu messen.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Laborwerte wie<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li>gro\u00dfes Blutbild, klinische Chemie<\/li>\n<li>Koagulogramm<\/li>\n<li>Gerinnungswerte sowie<\/li>\n<li>H\u00e4mostasesystem werden untersucht<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">Bei bestehender rezidivierender Epistaxis, bei der die Ursache unklar bleibt, ist eine <strong>Angiographie der Arteriae carotis externa <\/strong>und interna angezeigt, ggf. mit anschlie\u00dfender <span class=\"glossary-term\" data-title=\"Embolisation\" data-tooltip=\"Die Embolisation ist ein minimalinvasives endovaskul\u00e4res Verfahren, bei dem ein Blutgef\u00e4\u00df gezielt verschlossen wird, indem spezielle Materialien - Emboli - in das Gef\u00e4\u00dflumen eingebracht werden.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/embolisation\/\">Embolisation<\/span> der \u00c4ste, die die Epistaxis verursachen. <\/p>\n<h2 class=\"wp-block-heading\" id=\"behandlung-von-nasenbluten\"><strong>Behandlung von Nasenbluten<\/strong><\/h2>\n<h3 class=\"wp-block-heading\" id=\"erste-hilfe\"><strong>Erste Hilfe<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Als Erstes wird der Patient in die <strong>richtige K\u00f6rperlage<\/strong> \u2013 Aufrichtung mit nach vorne unten geneigtem Kopf \u2013 gebracht. Auf die Nasenwurzel und den Nacken wird eine <strong>kalte Kompresse<\/strong> gelegt und der <strong>Nasenfl\u00fcgel an das Septum gedr\u00fcckt<\/strong>; in die Nase kann ein in der 3 %-Wasserstoffperoxid-L\u00f6sung oder im lokalen Dekongestivum getr\u00e4nkter <strong>Streifen<\/strong> eingebracht werden. In den meisten F\u00e4llen hilft dieses Vorgehen, das Nasenbluten zu stoppen. Wenn es aber trotzdem nicht gestillt werden kann, ist medizinische Versorgung notwendig. <\/p>\n<div class=\"social-banner-block\">\n<div class=\"social-banner-content\">\n<p class=\"h5-title text-black\">Weitere wissenschaftlich korrekte Inhalte finden Sie in unseren sozialen Medien<\/p>\n<p><span class=\"social-banner-text text-grey\">Abonnieren Sie und verpassen Sie nicht die neuesten Ressourcen<\/span><\/p>\n<div class=\"social-links-wrapper\"><a class=\"social-icon-link\" href=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/facebook.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.instagram.com\/voka.io\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/insta.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.linkedin.com\/company\/voka-io\/posts\/?feedView=all\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/linkedin.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.youtube.com\/@vokaio\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/youtube.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.pinterest.com\/voka3danatomyandpathology\/\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/pinterest.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/www.tiktok.com\/@voka.io\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/tiktok.svg\" alt=\"social link\"><\/a><a class=\"social-icon-link\" href=\"https:\/\/discord.gg\/7ejUpq8DRR\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/Social%20Icons\/discord.svg\" alt=\"social link\"><\/a><\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"social-banner-image\" loading=\"lazy\" src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/common\/social-media-banner-mobile-image.webp\" alt=\"Banner background\"><\/div>\n<h3 class=\"wp-block-heading\" id=\"aerztliche-hilfe\"><strong>\u00c4rztliche Hilfe<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Es erfolgt eine vordere <strong>Nasentamponade<\/strong> mit einem h\u00e4mostatischen Schwamm, Blasenkatheter, Schwamm aus Ethylen-Vinylacetat mit Tuben oder mit Gazestreifen. Besonders verbreitet und am leichtesten zug\u00e4nglich, aber auch am schmerzhaftesten ist die <span class=\"glossary-term\" data-title=\"Tamponade\" data-tooltip=\"Tamponade (vom franz\u00f6sischen tampon \u2013 Pfropfen, Stopfen) ist ein medizinischer Begriff mit zwei Hauptbedeutungen: eine Behandlungsmethode und ein krankhafter Zustand. In beiden F\u00e4llen geht es darum, in einem bestimmten Hohlraum oder auf eine bestimmte Struktur Druck auszu\u00fcben.\" data-link=\"https:\/\/wiki.voka.io\/de\/glossar\/tamponade\/\">Tamponade<\/span> mit Gazestreifen. <\/p>\n<figure class=\"wp-block-video\" id=\"3d-animation-vordere-nasentamponade\"><video controls><source data-src=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/anterior%20nasal%20tamponade%20horizontal_watermark.webm\" type=\"video\/webm\"><\/source><\/video><figcaption class=\"wp-element-caption\">3D-Animation: vordere Nasentamponade<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Daf\u00fcr wird die Nasenschleimhaut mit einer An\u00e4sthetikum-L\u00f6sung bet\u00e4ubt, ein in bakterizide Salbe bzw. Vaseline getr\u00e4nkter Gazestreifen 70 bis 100 cm lang wird in den Nasenvorhof bis auf Choane eingebracht und von unten nach oben in Schichten aufgelegt, bis die gesamte Nasenhaupth\u00f6hle gef\u00fcllt ist. Zus\u00e4tzlich wird die Einlage mit Aminocaprons\u00e4ure oder Fibrin getr\u00e4nkt. F\u00fcr ein besseres Ergebnis bleibt die Nasenhaupth\u00f6hle \u00fcber 3 bis 5 Tage tamponiert, bis ein festes Blutgerinnsel gebildet ist; zur Prophylaxe bakterieller Komplikationen werden orale Antibiotika verordnet sowie regelm\u00e4\u00dfige Tr\u00e4nkung des Gazestreifens mit antiseptischen L\u00f6sungen eingesetzt, wonach die Tamponade entfernt wird. <\/p>\n<p class=\"wp-block-paragraph\">In einigen F\u00e4llen reicht die vordere Tamponade nicht aus und es kommt die <strong>hintere Nasentamponade<\/strong> zum Einsatz, bei der \u00fcber die Nasenhaupth\u00f6hle ein Tupfer bzw. ein Ballon in den Nasopharynx geschoben wird, wo er mit einer sterilen L\u00f6sung bef\u00fcllt wird. Nach der Ballonabdichtung erfolgt stets eine vordere Tamponade. Dieses Verfahren ist \u00e4u\u00dferst schmerzhaft und erfordert Sedation. Solche Patienten werden in der Regel auf einer Intensivstation versorgt. Bleibt diese Methode erfolglos, besteht die M\u00f6glichkeit einer <strong>Gef\u00e4\u00dfligatur bzw. -embolisation im Rahmen einer Angiographie<\/strong>.     <\/p>\n<p class=\"wp-block-paragraph\">Au\u00dfer den lokalen blutstillenden Verfahren werden den Patienten zus\u00e4tzlich <strong>H\u00e4mostatika<\/strong> (Etamsylat, Aminocapron- oder Tranexams\u00e4ure, Blutbestandteile wie Blutplasma und Thrombozytenkonzentrat) verordnet, die zirkulierende Blutmenge wird wiederhergestellt sowie grunds\u00e4tzlich alle blutungsf\u00f6rdernden Arzneimittel abgesetzt. <\/p>\n<p class=\"wp-block-paragraph\">Bei rezidivierenden Nasenbluten erfolgt eine <strong>Elektrokoagulation der Nasenh\u00f6hlengef\u00e4\u00dfe<\/strong><strong><\/strong>bzw. <strong>Schleimhautabl\u00f6sung<\/strong>, wodurch es zur Vernarbung und Sklerosierung des betroffenen Gef\u00e4\u00dfes kommt. <\/p>\n<p class=\"wp-block-paragraph\">Wenn die Ursache von Nasenbluten in einer Nebenerkrankung besteht, werden zur Therapie Fach\u00e4rzte verwandter Richtungen (Internist, Kardiologe, Hepatologe, H\u00e4matologe, Onkopathologe u.a.) herangezogen. <\/p>\n<div>\n<h2 class=\"faq-title h2-article\" id=\"faq\">FAQ<\/h2>\n<div class=\"faq-section\">\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">1. Woher kommt das Nasenbluten?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Am h\u00e4ufigsten blutet es aus dem Locus Kiesselbachi, einem Bereich an der Vorderseite der Nasenscheidewand mit einem dichten Gef\u00e4\u00dfnetz. Seltener liegt die Quelle tiefer, u.zw. in den hinteren Teilen der Nasenh\u00f6hle, wo gro\u00dfe Arterien (Siebbeinarterien, Arteria sphenopalatina) verlaufen. <\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">2. Wie gro\u00df ist die Gefahr von Nasenbluten?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Die Gefahr h\u00e4ngt vom Umfang des Blutverlustes ab. Starke Blutungen k\u00f6nnen zu einem hypovol\u00e4mischen Schock f\u00fchren, insbesondere bei Sch\u00e4digung der hinteren Arterien. H\u00e4ufige oder chronische Blutungen verursachen An\u00e4mie. Au\u00dferdem kann das Blut aspiriert werden oder bei unsachgem\u00e4\u00dfer Behandlung Komplikationen verursachen.   <\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">3. Was sollte man bei Nasenbluten NICHT tun?<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">\u2013 <strong>Neigen Sie Ihren Kopf zur\u00fcck<\/strong> \u2013 Blut kann in den Magen oder die Atemwege gelangen; <br \/>\u2013 <strong>Legen Sie sich hin<\/strong> \u2013 dies erh\u00f6ht das Risiko einer Aspiration; <br \/>\u2013 Nehmen Sie eine hei\u00dfe Dusche oder ein Bad \u2013 dies erh\u00f6ht den Blutverlust.  <\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<div class=\"faq-item faq-answer-hidden\">\n<div class=\"question-block\">\n<div class=\"faq-question\">\n<p class=\" text-black h5-title\">4. Ursachen f\u00fcr h\u00e4ufiges Nasenbluten bei Kindern<\/p>\n<\/div>\n<div class=\"faq-answer text-main-text-color main-text-medium\">Bei Kindern sind die h\u00e4ufigsten Ursachen: <br \/>\u2013 Trauma der Schleimhaut beim Bohren in der Nase oder beim Entfernen von Krusten; <br \/>\u2013 Atrophie der Schleimhaut vor dem Hintergrund trockener Luft; <br \/>\u2013 Rezidivierende Rhinitis und Adenoiditis; <br \/>\u2013 Nasale Fremdk\u00f6rper; <br \/>\u2013 Blutgerinnungsst\u00f6rungen; <br \/>\u2013 Hormonelle Besonderheiten in der Adoleszenz.<\/div>\n<\/div>\n<div class=\"expand-button-wrapper\"><button class=\"text-accent expand-button\">+<\/button><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-block sources-list-hidden\" id=\"liste-der-quellen\">\n<div class=\"sources-list-content\">\n<div class=\"sources-list-title\">\n<p class=\"small-text-bold text-black sources-list-title-text\">Liste der Quellen<\/p>\n<div class=\"sources-expand-button-wrapper-mobile\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<div class=\"sources-list-items\">\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">1.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">VOKA Katalog.<\/p>\n<p><span class=\"small-text-medium text-grey\">https:\/\/catalog.voka.io\/ <\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">2.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">Total Otolaryngology\u2014Head and Neck Surgery, Anthony P. Sclafani, Robin A. Dyleski, Michael J. Pitman, Stimson P. Schantz. Thieme Medical Publishers, Inc., 2015. ISBN 978-1-60406-646-3.<\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">3.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">\u0411\u0435\u0440\u0431\u043e\u043c \u0425. \u0411\u043e\u043b\u0435\u0437\u043d\u0438 \u0443\u0445\u0430, \u0433\u043e\u0440\u043b\u0430 \u0438 \u043d\u043e\u0441\u0430 \/ \u0425\u0430\u043d\u0441 \u0411\u0435\u0440\u0431\u043e\u043c, \u041e\u043b\u0438\u0432\u0435\u0440 \u041a\u0430\u0448\u043a\u0435, \u0422\u0430\u0434\u0435\u0443\u0441 \u041d\u0430\u0432\u043a\u0430, \u042d\u043d\u0434\u0440\u044e \u0421\u0432\u0438\u0444\u0442; \u043f\u0435\u0440. \u0441 \u0430\u043d\u0433\u043b. \u2013 2-\u0435 \u0438\u0437\u0434. \u2013 \u041c. : \u041c\u0415\u0414\u043f\u0440\u0435c\u0441-\u0438\u043d\u0444\u043e\u0440\u043c, 2016. \u2013 776 \u0441. : \u0438\u043b. ISBN 978-5-00030- 322-1.     <\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">4.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">Tabassom A, Dahlstrom JJ. Epistaxis. [Aktualisiert 2022 Sep 12]. In: StatPearls [Internet]. Treasure Island (FL): StatPearls Publishing; 2025 Jan-. Available from: <\/p>\n<p><span class=\"small-text-medium text-grey\">https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK435997\/<\/span><\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">5.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">Tunkel DE, Anne S, Payne SC, Ishman SL, Rosenfeld RM, Abramson PJ, Alikhaani JD, Benoit MM, Bercovitz RS, Brown MD, Chernobilsky B, Feldstein DA, Hackell JM, Holbrook EH, Holdsworth SM, Lin KW, Lind MM, Poetker DM, Riley CA, Schneider JS, Seidman MD, Vadlamudi V, Valdez TA, Nnacheta LC, Monjur TM. Clinical Practice Guideline: Nosebleed (Epistaxis). Otolaryngol Head Neck Surg. 2020 Jan;162(1_suppl):S1-S38. doi: 10.1177\/0194599819890327. PMID: 31910111.     <\/p>\n<\/div>\n<\/div>\n<div class=\"source-item\">\n<p class=\"main-text-semibold text-black\">6.<\/p>\n<div class=\"source-item-content\">\n<p class=\"main-text-semibold text-black\">Mylonas S, Skoulakis C, Nikolaidis V, Hajiioannou J. Epistaxis Treatment Options: Literature Review. Indian J Otolaryngol Head Neck Surg. 2023 Sep;75(3):2235-2244. doi: 10.1007\/s12070-023-03824-z. Epub 2023 May 8. PMID: 37636777; PMCID: PMC10447774.     <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sources-expand-button-wrapper\">\n<div class=\"sources-expand-button\"><svg width=\"32\" height=\"32\" viewbox=\"0 0 32 32\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 12L16 20L24 12\" stroke=\"#8C9AAB\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div>\n<\/div>\n<\/div>\n<p class=\"wp-block-paragraph\">\n","protected":false},"excerpt":{"rendered":"<p>Unter Nasenbluten (Epistaxis) versteht man das Austreten von Blut aus einem Blutgef\u00e4\u00df der Nasenh\u00f6hle durch die St\u00f6rung seiner Integrit\u00e4t oder Permeabilit\u00e4t. Es ist eine der h\u00e4ufigsten Blutungen. Klassifikation Lokalisation &#8211; anteriore Blutung&#8211; posteriore Blutung \u00c4tiologie &#8211; traumatisch&#8211; verursacht durch lokale Prozesse&#8211; verursacht durch h\u00e4ufige Krankheiten Blutverlust &#8211; schwache Blutung&#8211; m\u00e4\u00dfige Blutung&#8211; starke Blutung \u00c4tiologie Nasenbluten [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"template":"","diseases_category":[215],"class_list":["post-546","diseases_post","type-diseases_post","status-publish","hentry","diseases_category-hals-nasen-ohren-heilkunde"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nasenbluten \u2013 Ursachen, Symptome, erste Hilfe und Behandlung<\/title>\n<meta name=\"description\" content=\"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nasenbluten: Ursachen, erste Hilfe, Behandlung\" \/>\n<meta property=\"og:description\" content=\"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/\" \/>\n<meta property=\"og:site_name\" content=\"Voka Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T12:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/\"},\"author\":{\"name\":\"Danata A.\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/person\\\/b4a426e81487d8383acd6b38ef5679a6\"},\"headline\":\"Nasenbluten: Ursachen, erste Hilfe, Behandlung\",\"datePublished\":\"2025-04-04T10:36:13+00:00\",\"dateModified\":\"2026-01-13T12:49:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/\"},\"wordCount\":1520,\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/Otorhinolaryngology\\\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\\\/nosebleeds_1.webp\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/\",\"name\":\"Nasenbluten \u2013 Ursachen, Symptome, erste Hilfe und Behandlung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/Otorhinolaryngology\\\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\\\/nosebleeds_1.webp\",\"datePublished\":\"2025-04-04T10:36:13+00:00\",\"dateModified\":\"2026-01-13T12:49:12+00:00\",\"description\":\"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/Otorhinolaryngology\\\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\\\/nosebleeds_1.webp\",\"contentUrl\":\"https:\\\/\\\/storage.googleapis.com\\\/dev_wiki_voka_io_303011\\\/articles\\\/Otorhinolaryngology\\\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\\\/nosebleeds_1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/nasenbluten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hals-Nasen-Ohren-Heilkunde\",\"item\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/krankheit\\\/hals-nasen-ohren-heilkunde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nasenbluten: Ursachen, erste Hilfe, Behandlung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"name\":\"Voka Wiki\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\"},\"alternateName\":\"Anatomy & Pathology Wiki by VOKA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#organization\",\"name\":\"Voka 3D Anatomy & Pathology\",\"alternateName\":\"VOKA\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wiki.voka.io\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-voka-logo-1.png\",\"width\":70,\"height\":16,\"caption\":\"Voka 3D Anatomy & Pathology\"},\"image\":{\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VOKA3DAnatomyAndPathology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/voka.io\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voka-io\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqGGuOEpr62ScH8Pjk2q5zw\\\/videos\",\"https:\\\/\\\/www.pinterest.com\\\/VokaAnatomyPro\\\/\",\"https:\\\/\\\/www.threads.com\\\/@voka.io\"],\"description\":\"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.\",\"email\":\"info@voka.io\",\"telephone\":\"+1 814 351 4442\",\"legalName\":\"Voka 3D Anatomy & Pathology\",\"foundingDate\":\"2017-02-12\",\"naics\":\"541512\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/redaktionsrichtlinien\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wiki.voka.io\\\/de\\\/#\\\/schema\\\/person\\\/b4a426e81487d8383acd6b38ef5679a6\",\"name\":\"Danata A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g\",\"caption\":\"Danata A.\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nasenbluten \u2013 Ursachen, Symptome, erste Hilfe und Behandlung","description":"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/","og_locale":"de_DE","og_type":"article","og_title":"Nasenbluten: Ursachen, erste Hilfe, Behandlung","og_description":"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.","og_url":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/","og_site_name":"Voka Wiki","article_publisher":"https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","article_modified_time":"2026-01-13T12:49:12+00:00","og_image":[{"url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#article","isPartOf":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/"},"author":{"name":"Danata A.","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/person\/b4a426e81487d8383acd6b38ef5679a6"},"headline":"Nasenbluten: Ursachen, erste Hilfe, Behandlung","datePublished":"2025-04-04T10:36:13+00:00","dateModified":"2026-01-13T12:49:12+00:00","mainEntityOfPage":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/"},"wordCount":1520,"publisher":{"@id":"https:\/\/wiki.voka.io\/de\/#organization"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/","url":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/","name":"Nasenbluten \u2013 Ursachen, Symptome, erste Hilfe und Behandlung","isPartOf":{"@id":"https:\/\/wiki.voka.io\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#primaryimage"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp","datePublished":"2025-04-04T10:36:13+00:00","dateModified":"2026-01-13T12:49:12+00:00","description":"Nasenbluten: Ursachen, Symptome, klinische Erscheinungen, Diagnostik, Erste-Hilfe-Ma\u00dfnahmen und moderne Behandlungsmethoden bei Erwachsenen und Kindern.","breadcrumb":{"@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#primaryimage","url":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp","contentUrl":"https:\/\/storage.googleapis.com\/dev_wiki_voka_io_303011\/articles\/Otorhinolaryngology\/Nosebleeds%3A%20Causes%2C%20First%20Aid%2C%20Treatment\/nosebleeds_1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/nasenbluten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.voka.io\/de\/"},{"@type":"ListItem","position":2,"name":"Hals-Nasen-Ohren-Heilkunde","item":"https:\/\/wiki.voka.io\/de\/krankheit\/hals-nasen-ohren-heilkunde\/"},{"@type":"ListItem","position":3,"name":"Nasenbluten: Ursachen, erste Hilfe, Behandlung"}]},{"@type":"WebSite","@id":"https:\/\/wiki.voka.io\/de\/#website","url":"https:\/\/wiki.voka.io\/de\/","name":"Voka Wiki","description":"","publisher":{"@id":"https:\/\/wiki.voka.io\/de\/#organization"},"alternateName":"Anatomy & Pathology Wiki by VOKA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wiki.voka.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wiki.voka.io\/de\/#organization","name":"Voka 3D Anatomy & Pathology","alternateName":"VOKA","url":"https:\/\/wiki.voka.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","contentUrl":"https:\/\/wiki.voka.io\/wp-content\/uploads\/2025\/02\/cropped-voka-logo-1.png","width":70,"height":16,"caption":"Voka 3D Anatomy & Pathology"},"image":{"@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VOKA3DAnatomyAndPathology\/","https:\/\/www.instagram.com\/voka.io\/","https:\/\/www.linkedin.com\/company\/voka-io\/","https:\/\/www.youtube.com\/channel\/UCqGGuOEpr62ScH8Pjk2q5zw\/videos","https:\/\/www.pinterest.com\/VokaAnatomyPro\/","https:\/\/www.threads.com\/@voka.io"],"description":"VOKA.io offers 3D medical animations and custom 3D modeling services. Our product, VOKA 3D Anatomy & Pathology, is a digital atlas with over 1,000 detailed 3D models of human anatomy and pathology, designed for medical education, training, and patient communication.","email":"info@voka.io","telephone":"+1 814 351 4442","legalName":"Voka 3D Anatomy & Pathology","foundingDate":"2017-02-12","naics":"541512","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/wiki.voka.io\/de\/redaktionsrichtlinien\/"},{"@type":"Person","@id":"https:\/\/wiki.voka.io\/de\/#\/schema\/person\/b4a426e81487d8383acd6b38ef5679a6","name":"Danata A.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17b61e87bc892ef9555b6080655463c63eb46025ed870850eaa2472678817ed6?s=96&d=mm&r=g","caption":"Danata A."}}]}},"_links":{"self":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/diseases_post\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/diseases_post"}],"about":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/types\/diseases_post"}],"author":[{"embeddable":true,"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/users\/4"}],"wp:attachment":[{"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"diseases_category","embeddable":true,"href":"https:\/\/wiki.voka.io\/de\/wp-json\/wp\/v2\/diseases_category?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}